{"id":11194,"date":"2023-02-27T21:06:52","date_gmt":"2023-02-27T21:06:52","guid":{"rendered":"https:\/\/uavlatam.com\/uavlatam\/"},"modified":"2025-03-12T18:16:10","modified_gmt":"2025-03-12T18:16:10","slug":"uavlatam-drones-e-inteligencia-artificial","status":"publish","type":"page","link":"https:\/\/uavlatam.com\/pt-br\/","title":{"rendered":"UAVLatam &#8211; Drones e Intelig\u00eancia Artificial"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"11194\" class=\"elementor elementor-11194 elementor-10793\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d10cd4f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d10cd4f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-57300ea\" data-id=\"57300ea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4829685 elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"4829685\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/06\/cropped-logo-uav-blanco-1-e1718906915187.png\" class=\"attachment-large size-large wp-image-15957\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/06\/cropped-logo-uav-blanco-1-e1718906915187.png 512w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/06\/cropped-logo-uav-blanco-1-e1718906915187-300x300.png 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/06\/cropped-logo-uav-blanco-1-e1718906915187-150x150.png 150w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/06\/cropped-logo-uav-blanco-1-e1718906915187-270x270.png 270w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/06\/cropped-logo-uav-blanco-1-e1718906915187-192x192.png 192w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/06\/cropped-logo-uav-blanco-1-e1718906915187-180x180.png 180w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/06\/cropped-logo-uav-blanco-1-e1718906915187-32x32.png 32w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2dbe0ba\" data-id=\"2dbe0ba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2fe913 elementor-icon-list--layout-inline elementor-mobile-align-center elementor-widget-mobile__width-inherit elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c2fe913\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/uavlatam.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#inicio\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Come\u00e7ar<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#presencia\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sobre N\u00f3s<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#soluciones\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Solu\u00e7\u00f5es<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#blog\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Blog<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#contactanos\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Contate-nos<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-660e725\" data-id=\"660e725\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9109ec0 elementor-widget elementor-widget-wpml-language-switcher\" data-id=\"9109ec0\" data-element_type=\"widget\" data-widget_type=\"wpml-language-switcher.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wpml-elementor-ls\">\n<div class=\"wpml-ls-statics-shortcode_actions wpml-ls wpml-ls-legacy-list-horizontal\">\n\t<ul><li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-en wpml-ls-first-item wpml-ls-item-legacy-list-horizontal\">\n\t\t\t\t<a href=\"https:\/\/uavlatam.com\/en\/\" class=\"wpml-ls-link\">\n                                                        <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/uavlatam.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/en.png\"\n            alt=\"\"\n            width=18\n            height=12\n    \/><span class=\"wpml-ls-native\" lang=\"en\">Eng<\/span><\/a>\n\t\t\t<\/li><li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-es wpml-ls-item-legacy-list-horizontal\">\n\t\t\t\t<a href=\"https:\/\/uavlatam.com\" class=\"wpml-ls-link\">\n                                                        <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/uavlatam.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/es.png\"\n            alt=\"\"\n            width=18\n            height=12\n    \/><span class=\"wpml-ls-native\" lang=\"es\">Esp<\/span><\/a>\n\t\t\t<\/li><li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-pt-br wpml-ls-current-language wpml-ls-last-item wpml-ls-item-legacy-list-horizontal\">\n\t\t\t\t<a href=\"https:\/\/uavlatam.com\/pt-br\/\" class=\"wpml-ls-link\">\n                                                        <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/uavlatam.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/pt-br.png\"\n            alt=\"\"\n            width=18\n            height=12\n    \/><span class=\"wpml-ls-native\">Por<\/span><\/a>\n\t\t\t<\/li><\/ul>\n<\/div>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95ee54f elementor-widget elementor-widget-text-editor\" data-id=\"95ee54f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Piloto de drone? \u00a0\u00a0 \u00a0<a href=\"https:\/\/pilotlink.lat\"><span style=\"color: #ffffff;\"><u>Trabalhe conosco<\/u><\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-83823f8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"83823f8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f3010e1\" data-id=\"f3010e1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca49ca2 elementor-widget elementor-widget-image\" data-id=\"ca49ca2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/06\/Logo-UAV-Latam-sin-slogan-COLOR.png\" class=\"attachment-large size-large wp-image-15954\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/06\/Logo-UAV-Latam-sin-slogan-COLOR.png 400w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/06\/Logo-UAV-Latam-sin-slogan-COLOR-300x300.png 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/06\/Logo-UAV-Latam-sin-slogan-COLOR-150x150.png 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c6afbd2\" data-id=\"c6afbd2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8f00a2 elementor-icon-list--layout-inline elementor-mobile-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e8f00a2\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#inicio\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Come\u00e7ar<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#presencia\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sobre n\u00f3s<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#soluciones\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Solu\u00e7\u00f5es<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/uavlatam.com\/pt-br\/blogue\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Blog<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#contactanos\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Contate-nos<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b7d3f6b\" data-id=\"b7d3f6b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba84372 elementor-widget elementor-widget-wpml-language-switcher\" data-id=\"ba84372\" data-element_type=\"widget\" data-widget_type=\"wpml-language-switcher.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wpml-elementor-ls\">\n<div class=\"wpml-ls-statics-shortcode_actions wpml-ls wpml-ls-legacy-list-horizontal\">\n\t<ul><li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-en wpml-ls-first-item wpml-ls-item-legacy-list-horizontal\">\n\t\t\t\t<a href=\"https:\/\/uavlatam.com\/en\/\" class=\"wpml-ls-link\">\n                                                        <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/uavlatam.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/en.png\"\n            alt=\"\"\n            width=18\n            height=12\n    \/><span class=\"wpml-ls-native\" lang=\"en\">Eng<\/span><\/a>\n\t\t\t<\/li><li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-es wpml-ls-item-legacy-list-horizontal\">\n\t\t\t\t<a href=\"https:\/\/uavlatam.com\" class=\"wpml-ls-link\">\n                                                        <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/uavlatam.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/es.png\"\n            alt=\"\"\n            width=18\n            height=12\n    \/><span class=\"wpml-ls-native\" lang=\"es\">Esp<\/span><\/a>\n\t\t\t<\/li><li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-pt-br wpml-ls-current-language wpml-ls-last-item wpml-ls-item-legacy-list-horizontal\">\n\t\t\t\t<a href=\"https:\/\/uavlatam.com\/pt-br\/\" class=\"wpml-ls-link\">\n                                                        <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/uavlatam.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/pt-br.png\"\n            alt=\"\"\n            width=18\n            height=12\n    \/><span class=\"wpml-ls-native\">Por<\/span><\/a>\n\t\t\t<\/li><\/ul>\n<\/div>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c138442 elementor-widget elementor-widget-text-editor\" data-id=\"c138442\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Piloto de drone? \u00a0\u00a0<\/p><p><span style=\"text-decoration: underline; color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/pilotlink.lat\">Trabalhe conosco<\/a><\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2af9234 elementor-align-justify elementor-widget-mobile__width-initial elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"2af9234\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contactanos\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CONTATE-NOS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49c63af elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"49c63af\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6703f00\" data-id=\"6703f00\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8d92f8 elementor--h-position-center elementor--v-position-middle elementor-widget elementor-widget-slides\" data-id=\"e8d92f8\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;none&quot;,&quot;transition_speed&quot;:1500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.21.0 - 20-05-2024 *\/\n.elementor-slides .swiper-slide-bg{background-size:cover;background-position:50%;background-repeat:no-repeat;min-width:100%;min-height:100%}.elementor-slides .swiper-slide-inner{background-repeat:no-repeat;background-position:50%;position:absolute;top:0;left:0;bottom:0;right:0;padding:50px;margin:auto}.elementor-slides .swiper-slide-inner,.elementor-slides .swiper-slide-inner:hover{color:#fff;display:flex}.elementor-slides .swiper-slide-inner .elementor-background-overlay{position:absolute;z-index:0;top:0;bottom:0;left:0;right:0}.elementor-slides .swiper-slide-inner .elementor-slide-content{position:relative;z-index:1;width:100%}.elementor-slides .swiper-slide-inner .elementor-slide-heading{font-size:35px;font-weight:700;line-height:1}.elementor-slides .swiper-slide-inner .elementor-slide-description{font-size:17px;line-height:1.4}.elementor-slides .swiper-slide-inner .elementor-slide-description:not(:last-child),.elementor-slides .swiper-slide-inner .elementor-slide-heading:not(:last-child){margin-bottom:30px}.elementor-slides .swiper-slide-inner .elementor-slide-button{border:2px solid #fff;color:#fff;background:transparent;display:inline-block}.elementor-slides .swiper-slide-inner .elementor-slide-button,.elementor-slides .swiper-slide-inner .elementor-slide-button:hover{background:transparent;color:inherit;text-decoration:none}.elementor--v-position-top .swiper-slide-inner{align-items:flex-start}.elementor--v-position-bottom .swiper-slide-inner{align-items:flex-end}.elementor--v-position-middle .swiper-slide-inner{align-items:center}.elementor--h-position-left .swiper-slide-inner{justify-content:flex-start}.elementor--h-position-right .swiper-slide-inner{justify-content:flex-end}.elementor--h-position-center .swiper-slide-inner{justify-content:center}body.rtl .elementor-widget-slides .elementor-swiper-button-next{left:10px;right:auto}body.rtl .elementor-widget-slides .elementor-swiper-button-prev{right:10px;left:auto}.elementor-slides-wrapper div:not(.swiper-slide)>.swiper-slide-inner{display:none}@media (max-width:767px){.elementor-slides .swiper-slide-inner{padding:30px}.elementor-slides .swiper-slide-inner .elementor-slide-heading{font-size:23px;line-height:1;margin-bottom:15px}.elementor-slides .swiper-slide-inner .elementor-slide-description{font-size:13px;line-height:1.4;margin-bottom:15px}}<\/style>\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" dir=\"ltr\" data-animation=\"\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-ec6fe83 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Transforme sua empresa com solu\u00e7\u00f5es avan\u00e7adas de drones <\/div><div class=\"elementor-slide-description\">Minimize riscos com <u> solu\u00e7\u00f5es anti-drone.<\/u><\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-6a236d1 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Transforme sua empresa com solu\u00e7\u00f5es avan\u00e7adas de drones<\/div><div class=\"elementor-slide-description\">Proteja ativos com <u> solu\u00e7\u00f5es de vigil\u00e2ncia a\u00e9rea. \u200b <\/u><\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-9cbb81c swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Transforme sua empresa com solu\u00e7\u00f5es avan\u00e7adasde  drones<\/div><div class=\"elementor-slide-description\">Otimize recursos com  <u>solu\u00e7\u00f5es de agricultura de precis\u00e3o. <\/u><\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-bccbc14 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Transforme sua empresa com solu\u00e7\u00f5es avan\u00e7adas de drones<\/div><div class=\"elementor-slide-description\">Inspecione infraestrutura cr\u00edtica de forma eficiente e profissional.<\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aaebdfa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aaebdfa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d409312\" data-id=\"d409312\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f43fe31 elementor-widget__width-initial elementor-widget elementor-widget-tp-clients-listout\" data-id=\"f43fe31\" data-element_type=\"widget\" data-widget_type=\"tp-clients-listout.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"pt-plus-clients-post-list\" class=\"clients-list post6a56d2fc2c7bb  list-carousel-slick client-style-1 \"   data-slider_direction=\"false\" data-slide_speed=\"1500\" data-slider_desktop_column=\"8\" data-steps_slide=\"1\" data-slider_draggable=\"false\" data-multi_drag=\"false\" data-slider_infinite=\"true\" data-slider_pause_hover=\"false\" data-slider_adaptive_height=\"false\" data-slider_animation=\"linear\" data-slider_autoplay=\"true\" data-autoplay_speed=\"800\" data-slider_tablet_column=\"5\" data-tablet_steps_slide=\"1\" data-slider_responsive_tablet=\"yes\" data-tablet_slider_draggable=\"false\" data-tablet_slider_infinite=\"true\" data-tablet_slider_autoplay=\"true\" data-tablet_autoplay_speed=\"800\" data-tablet_slider_dots=\"false\" data-tablet_slider_arrows=\"false\" data-tablet_slider_rows=\"1\" data-tablet_center_mode=\"false\"  data-tablet_center_padding=\"0\"  data-slider_mobile_column=\"3\" data-mobile_steps_slide=\"1\" data-slider_responsive_mobile=\"yes\" data-mobile_slider_draggable=\"false\" data-mobile_slider_infinite=\"true\" data-mobile_slider_autoplay=\"true\" data-mobile_autoplay_speed=\"800\" data-mobile_slider_dots=\"false\" data-mobile_slider_arrows=\"false\" data-mobile_slider_rows=\"1\" data-mobile_center_mode=\"false\"  data-mobile_center_padding=\"0\" data-slider_dots=\"false\" data-slider_dots_style=\"slick-dots \" data-slider_arrows=\"false\" data-slider_arrows_style=\"\"  data-arrows_position=\"\"  data-arrow_bg_color=\"\"  data-arrow_icon_color=\"\"  data-arrow_hover_bg_color=\"\"  data-arrow_hover_icon_color=\"\"  data-slider_center_mode=\"false\"  data-center_padding=\"0\"  data-scale_center_slide=\"1\"  data-scale_normal_slide=\"0.8\"  data-opacity_normal_slide=\"0.7\"  data-slider_rows=\"1\"  data-id=\"post6a56d2fc2c7bb\" data-style=\"style-1\"  data-enable-isotope=\"1\"><div class=\"tp-row post-inner-loop    flex-wrap tp-align-items-center post6a56d2fc2c7bb\"><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/VHIVE.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/VHIVE.png 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/VHIVE-300x300.png 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/VHIVE-150x150.png 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/Grupo-Vision.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/Grupo-Vision.png 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/Grupo-Vision-300x300.png 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/Grupo-Vision-150x150.png 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/ENEL.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/ENEL.png 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/ENEL-300x300.png 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/ENEL-150x150.png 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/Arcor.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/Arcor.png 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/Arcor-300x300.png 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/Arcor-150x150.png 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/TW-SOLAR.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/TW-SOLAR.png 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/TW-SOLAR-300x300.png 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/TW-SOLAR-150x150.png 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/Sitstema-Portuario-Veracruzano.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/Sitstema-Portuario-Veracruzano.jpg 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/Sitstema-Portuario-Veracruzano-300x300.jpg 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/Sitstema-Portuario-Veracruzano-150x150.jpg 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/ETESA.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/ETESA.png 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/ETESA-300x300.png 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/ETESA-150x150.png 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/OLEODUCTO-CHILENO.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/OLEODUCTO-CHILENO.jpg 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/OLEODUCTO-CHILENO-300x300.jpg 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/OLEODUCTO-CHILENO-150x150.jpg 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/GRUPO-OTI.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/GRUPO-OTI.png 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/GRUPO-OTI-300x300.png 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/GRUPO-OTI-150x150.png 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/OHLA-1.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/OHLA-1.png 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/OHLA-1-300x300.png 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/OHLA-1-150x150.png 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/CELIMA.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/CELIMA.png 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/CELIMA-300x300.png 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/CELIMA-150x150.png 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/TGS.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/TGS.png 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/TGS-300x300.png 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/TGS-150x150.png 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/agnico-eagle.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/agnico-eagle.png 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/agnico-eagle-300x300.png 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/agnico-eagle-150x150.png 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/WFP.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/WFP.png 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/WFP-300x300.png 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/WFP-150x150.png 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/EISA.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/EISA.png 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/EISA-300x300.png 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/EISA-150x150.png 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/EBSA.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/EBSA.jpg 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/EBSA-300x300.jpg 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/EBSA-150x150.jpg 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/SUNGROW.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/SUNGROW.png 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/SUNGROW-300x300.png 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/SUNGROW-150x150.png 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/GLOBHE.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/GLOBHE.jpg 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/GLOBHE-300x300.jpg 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/GLOBHE-150x150.jpg 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/APM-Terminals.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/APM-Terminals.jpg 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/APM-Terminals-300x300.jpg 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/APM-Terminals-150x150.jpg 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/STORK.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/STORK.png 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/STORK-300x300.png 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/STORK-150x150.png 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/TRANSENER.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/TRANSENER.png 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/TRANSENER-300x300.png 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/TRANSENER-150x150.png 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><div class=\"grid-item flex-column flex-wrap      \">\t\t<div class=\"client-post-content\">\n\t\t\t<div class=\"client-content-logo\">\n\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\"> \n<div class=\"client-featured-logo\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/Lincuna.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/Lincuna.png 350w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/Lincuna-300x300.png 300w, https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/07\/Lincuna-150x150.png 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t<\/span>\n<\/div><\/a>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db10f9e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db10f9e\" data-element_type=\"section\" id=\"presencia\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d76a289\" data-id=\"d76a289\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d715df elementor-widget elementor-widget-heading\" data-id=\"6d715df\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">QUEM SOMOS<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12e2556 elementor-widget elementor-widget-heading\" data-id=\"12e2556\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><h2 style=\"white-space-collapse: collapse;\"><font style=\"vertical-align: inherit;\">L\u00cdDERES DE SERVI\u00c7OS COM DRONES NA AM\u00c9RICA LATINA<\/font><\/h2><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51f58f5 elementor-widget elementor-widget-text-editor\" data-id=\"51f58f5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Somos integradores de solu\u00e7\u00f5es tecnol\u00f3gicas para <b>seguran\u00e7a, defesa e monitoramento<\/b> de grandes espa\u00e7os e infraestruturas cr\u00edticas.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6329d97 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"6329d97\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJ0eXBlIjoidmlkZW8iLCJ2aWRlb1R5cGUiOiJ5b3V0dWJlIiwidXJsIjoiaHR0cHM6XC9cL3d3dy55b3V0dWJlLmNvbVwvZW1iZWRcL2cxbm1XWU03X3ZjP2ZlYXR1cmU9b2VtYmVkIn0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-play\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">olha o v\u00eddeo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5018c2b elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-global elementor-global-14495 elementor-widget-tp-accordion\" data-id=\"5018c2b\" data-element_type=\"widget\" data-widget_type=\"tp-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"theplus-accordion-wrapper elementor-accordion  tp-stageraccr tp-scrolltopacc  \" id=\"accordion6a56d2fccea81\" data-accordion-id=\"accordion6a56d2fccea81\" data-connection=\"\" data-accordion-type=\"accordion\"    data-stager-vd-accr=\"500\" data-stager-gap-accr=\"500\" data-scroll-top-accr=\"yes\" data-scroll-top-speed-accr=\"500\" data-scroll-top-offset-accr=\"0\" role=\"tablist\" > \n\t\t\n\t\t\t\t\t\t<div class=\"theplus-accordion-item\" >\n\t\t\t\t\t<div id=\"elementor-tab-title-8391\" class=\"elementor-tab-title plus-accordion-header 0 text-left \" tabindex=\"8391\" data-tab=\"1\" role=\"tab\" aria-controls=\"elementor-tab-content-8391\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t <span style=\"width:100%\"><img decoding=\"async\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2021\/09\/ar.svg\" style=\"width:15px; margin-right:5px\">Argentina<\/span>\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-chevron-down\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-chevron-up\"><\/i><\/span>\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-content-8391\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0 \" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8391\">\n\t\t\t\t\t\t\t<div class=\"plus-content-editor\" ><table style=\"height: 185px;\" width=\"233\"><tbody><tr><td>\u00a0<\/td><\/tr><tr><td><span style=\"color: #999999;\">Contato<\/span><\/td><\/tr><tr><td>Guillermo Bergelund<\/td><\/tr><tr><td><a href=\"mailto:gbergelund@uavlatam.com\">gbergelund@uavlatam.com<\/a><\/td><td><a style=\"color: #2e3b56;\" href=\"mailto:mmarcati@uavlatam.com\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11369 size-full\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-envelope.png\" alt=\"\" width=\"20\" height=\"32\" \/><\/a><\/td><\/tr><tr><td><a href=\"https:\/\/wa.me\/51989256123\">+51989256123<\/a><\/td><td><a href=\"https:\/\/wa.me\/5491138720334\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11372 \" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-phone.png\" alt=\"\" width=\"19\" height=\"19\" \/><\/a><\/td><\/tr><tr><td>\u00a0<\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div> \n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"theplus-accordion-item\" >\n\t\t\t\t\t<div id=\"elementor-tab-title-8392\" class=\"elementor-tab-title plus-accordion-header 0 text-left \" tabindex=\"8392\" data-tab=\"2\" role=\"tab\" aria-controls=\"elementor-tab-content-8392\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t <span style=\"width:100%\"><img decoding=\"async\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2021\/09\/Flag_of_Brazil.svg\" style=\"width:15px; margin-right:5px\">Brasil<\/span>\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-chevron-down\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-chevron-up\"><\/i><\/span>\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-content-8392\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0 \" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8392\">\n\t\t\t\t\t\t\t<div class=\"plus-content-editor\" ><table style=\"height: 185px;\" width=\"233\"><tbody><tr><td>\u00a0<\/td><\/tr><tr><td><span style=\"color: #999999;\">Contato<\/span><\/td><\/tr><tr><td>Guillermo Bergelund<\/td><\/tr><tr><td><a href=\"mailto:gbergelund@uavlatam.com\">gbergelund@uavlatam.com<\/a><\/td><td><a style=\"color: #2e3b56;\" href=\"mailto:mmarcati@uavlatam.com\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11369 size-full\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-envelope.png\" alt=\"\" width=\"20\" height=\"32\" \/><\/a><\/td><\/tr><tr><td><a href=\"https:\/\/wa.me\/51989256123\">+51989256123<\/a><\/td><td><a href=\"https:\/\/wa.me\/5491138720334\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11372 \" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-phone.png\" alt=\"\" width=\"19\" height=\"19\" \/><\/a><\/td><\/tr><tr><td>\u00a0<\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div> \n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"theplus-accordion-item\" >\n\t\t\t\t\t<div id=\"elementor-tab-title-8393\" class=\"elementor-tab-title plus-accordion-header 0 text-left \" tabindex=\"8393\" data-tab=\"3\" role=\"tab\" aria-controls=\"elementor-tab-content-8393\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t <span style=\"width:100%\"><img decoding=\"async\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2021\/10\/Flag_of_Chile.svg\" style=\"width:15px; margin-right:5px\">Chile<\/span>\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-chevron-down\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-chevron-up\"><\/i><\/span>\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-content-8393\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0 \" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8393\">\n\t\t\t\t\t\t\t<div class=\"plus-content-editor\" ><table style=\"height: 285px;\" width=\"214\"><tbody><tr><td>\u00a0<\/td><\/tr><tr><td><span style=\"color: #999999;\">Contacto de ventas<\/span><\/td><\/tr><tr><td>Mar\u00eda Beatriz Quiros\u00a0<\/td><\/tr><tr><td><a style=\"color: #2e3b56;\" href=\"mailto:mbquiros@uavlatam.com\">mbquiros@uavlatam.com<\/a><\/td><td><a style=\"color: #000000;\" href=\"mailto:acosta@uavlatam.com\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11369\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-envelope.png\" alt=\"\" width=\"20\" height=\"32\" \/><\/a><\/td><\/tr><tr><td><a style=\"color: #2e3b56;\" href=\"https:\/\/wa.me\/56998747462\" target=\"_blank;\">+56 9 98747462<\/a><\/td><td><a href=\"https:\/\/wa.me\/56992221540\" target=\"_blank;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11372 size-full\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-phone.png\" alt=\"\" width=\"20\" height=\"41\" \/><\/a><\/td><\/tr><tr><td>\u00a0<\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div> \n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"theplus-accordion-item\" >\n\t\t\t\t\t<div id=\"elementor-tab-title-8394\" class=\"elementor-tab-title plus-accordion-header 0 text-left \" tabindex=\"8394\" data-tab=\"4\" role=\"tab\" aria-controls=\"elementor-tab-content-8394\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t <span style=\"width:100%\"><img decoding=\"async\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2021\/06\/COLOMBIA-01-1.svg\" style=\"width:15px; margin-right:5px\">Colombia<\/span>\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-chevron-down\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-chevron-up\"><\/i><\/span>\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-content-8394\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0 \" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8394\">\n\t\t\t\t\t\t\t<div class=\"plus-content-editor\" ><table style=\"height: 260px;\" width=\"205\"><tbody><tr><td>\u00a0<\/td><\/tr><tr><td><span style=\"color: #999999;\">Contacto de ventas<\/span><\/td><\/tr><tr><td>Rodrigo Medina<\/td><\/tr><tr><td><a style=\"color: #2e3b56;\" href=\"mailto:rmedina@uavlatam.com\">rmedina@uavlatam.com<\/a><\/td><td><a style=\"color: #2e3b56;\" href=\"mailto:rmedina@uavlatam.com\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11369\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-envelope.png\" alt=\"\" width=\"20\" height=\"32\" \/><\/a><\/td><\/tr><tr><td><a style=\"color: #2e3b56;\" href=\"https:\/\/wa.me\/573144391738\" target=\"_blank;\">+57 3144391738<\/a><\/td><td><a href=\"https:\/\/wa.me\/573144391738\" target=\"_blank;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11372 size-full\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-phone.png\" alt=\"\" width=\"20\" height=\"41\" \/><\/a><\/td><\/tr><tr><td>\u00a0<\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div> \n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"theplus-accordion-item\" >\n\t\t\t\t\t<div id=\"elementor-tab-title-8395\" class=\"elementor-tab-title plus-accordion-header 0 text-left \" tabindex=\"8395\" data-tab=\"5\" role=\"tab\" aria-controls=\"elementor-tab-content-8395\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t <span style=\"width:100%\"><img decoding=\"async\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2021\/06\/cr.svg\" style=\"width:15px; margin-right:5px\">Costa Rica<\/span>\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-chevron-down\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-chevron-up\"><\/i><\/span>\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-content-8395\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0 \" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8395\">\n\t\t\t\t\t\t\t<div class=\"plus-content-editor\" ><table><tbody><tr><td>\u00a0<\/td><\/tr><tr><td><span style=\"color: #999999;\">Contacto de ventas<\/span><\/td><\/tr><tr><td>Francisco Fallas<\/td><\/tr><tr><td><a style=\"color: #2e3b56;\" href=\"mailto:ffallas@uavlatam.com\">ffallas@uavlatam.com<\/a><\/td><td><a style=\"color: #2e3b56;\" href=\"mailto:ffallas@uavlatam.com\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11369\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-envelope.png\" alt=\"\" width=\"20\" height=\"32\" \/><\/a><\/td><\/tr><tr><td><a style=\"color: #2e3b56;\" href=\"https:\/\/wa.me\/50683853934\" target=\"_blank;\">+506 8385-3934<\/a><\/td><td><a href=\"https:\/\/wa.me\/50683853934\" target=\"_blank;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11372 size-full\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-phone.png\" alt=\"\" width=\"20\" height=\"41\" \/><\/a><\/td><\/tr><tr><td>\u00a0<\/td><td><a href=\"https:\/\/uavlatam.com\/uavlatam-costa-rica\/\" target=\"_blank;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11366\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-world.png\" alt=\"\" width=\"20\" height=\"37\" \/><\/a><\/td><\/tr><\/tbody><\/table><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div> \n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"theplus-accordion-item\" >\n\t\t\t\t\t<div id=\"elementor-tab-title-8396\" class=\"elementor-tab-title plus-accordion-header 0 text-left \" tabindex=\"8396\" data-tab=\"6\" role=\"tab\" aria-controls=\"elementor-tab-content-8396\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t <span style=\"width:100%\"><img decoding=\"async\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2021\/09\/mx.svg\" style=\"width:15px; margin-right:5px\">M\u00e9xico<\/span>\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-chevron-down\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-chevron-up\"><\/i><\/span>\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-content-8396\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0 \" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8396\">\n\t\t\t\t\t\t\t<div class=\"plus-content-editor\" ><table><tbody><tr><td>\u00a0<\/td><\/tr><tr><td><span style=\"color: #999999;\">Contacto de ventas<\/span><\/td><\/tr><tr><td>Alicia Hern\u00e1ndez<\/td><\/tr><tr><td><a style=\"color: #2e3b56;\" href=\"mailto:ahernandez@uavlatam.com\">ahernandez@uavlatam.com<\/a><\/td><td><a style=\"color: #2e3b56;\" href=\"mailto:ahernandez@uavlatam.com\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11369\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-envelope.png\" alt=\"\" width=\"20\" height=\"32\" \/><\/a><\/td><\/tr><tr><td><a style=\"color: #2e3b56;\" href=\"https:\/\/wa.me\/524423787054\" target=\"_blank;\">+524423787054<\/a><\/td><td><a href=\"https:\/\/wa.me\/5214423787054\" target=\"_blank;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11372 size-full\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-phone.png\" alt=\"\" width=\"20\" height=\"41\" \/><\/a><\/td><\/tr><tr><td>\u00a0<\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div> \n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"theplus-accordion-item\" >\n\t\t\t\t\t<div id=\"elementor-tab-title-8397\" class=\"elementor-tab-title plus-accordion-header 0 text-left \" tabindex=\"8397\" data-tab=\"7\" role=\"tab\" aria-controls=\"elementor-tab-content-8397\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t <span style=\"width:100%\"><img decoding=\"async\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2021\/09\/pe.svg\" style=\"width:15px; margin-right:5px\">Per\u00fa<\/span>\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-chevron-down\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-chevron-up\"><\/i><\/span>\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-content-8397\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0 \" data-tab=\"7\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8397\">\n\t\t\t\t\t\t\t<div class=\"plus-content-editor\" ><table style=\"height: 185px;\" width=\"233\"><tbody><tr><td>\u00a0<\/td><\/tr><tr><td><span style=\"color: #999999;\">Contato<\/span><\/td><\/tr><tr><td>Guillermo Bergelund<\/td><\/tr><tr><td><a href=\"mailto:gbergelund@uavlatam.com\">gbergelund@uavlatam.com<\/a><\/td><td><a style=\"color: #2e3b56;\" href=\"mailto:mmarcati@uavlatam.com\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11369 size-full\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-envelope.png\" alt=\"\" width=\"20\" height=\"32\" \/><\/a><\/td><\/tr><tr><td><a href=\"https:\/\/wa.me\/51989256123\">+51989256123<\/a><\/td><td><a href=\"https:\/\/wa.me\/5491138720334\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11372 \" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-phone.png\" alt=\"\" width=\"19\" height=\"19\" \/><\/a><\/td><\/tr><tr><td>\u00a0<\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div> \n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"theplus-accordion-item\" >\n\t\t\t\t\t<div id=\"elementor-tab-title-8398\" class=\"elementor-tab-title plus-accordion-header 0 text-left \" tabindex=\"8398\" data-tab=\"8\" role=\"tab\" aria-controls=\"elementor-tab-content-8398\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t <span style=\"width:100%\"><img decoding=\"async\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2021\/07\/pa.svg\" style=\"width:15px; margin-right:5px\">Panam\u00e1<\/span>\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-chevron-down\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-chevron-up\"><\/i><\/span>\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-content-8398\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0 \" data-tab=\"8\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8398\">\n\t\t\t\t\t\t\t<div class=\"plus-content-editor\" ><table><tbody><tr><td>\u00a0<\/td><\/tr><tr><td><span style=\"color: #999999;\">Contacto de ventas<\/span><\/td><\/tr><tr><td>Eduardo L\u00f3pez<\/td><\/tr><tr><td><a style=\"color: #2e3b56;\" href=\"mailto:elopez@uavlatam.com\">el\u00f3pez@uavlatam.com<\/a><\/td><td><a style=\"color: #2e3b56;\" href=\"mailto:elopez@uavlatam.com\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11369\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-envelope.png\" alt=\"\" width=\"20\" height=\"32\" \/><\/a><\/td><\/tr><tr><td><a style=\"color: #2e3b56;\" href=\"https:\/\/wa.me\/50766196456\" target=\"_blank;\">+507 66196456<\/a><\/td><td><a href=\"https:\/\/wa.me\/50766196456\" target=\"_blank;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11372 size-full\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-phone.png\" alt=\"\" width=\"20\" height=\"41\" \/><\/a><\/td><\/tr><tr><td>\u00a0<\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div> \n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"theplus-accordion-item\" >\n\t\t\t\t\t<div id=\"elementor-tab-title-8399\" class=\"elementor-tab-title plus-accordion-header 0 text-left \" tabindex=\"8399\" data-tab=\"9\" role=\"tab\" aria-controls=\"elementor-tab-content-8399\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t <span style=\"width:100%\"><img decoding=\"async\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2021\/09\/rd.svg\" style=\"width:15px; margin-right:5px\">Rep\u00fablica Dominicana<\/span>\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-chevron-down\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-chevron-up\"><\/i><\/span>\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-content-8399\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0 \" data-tab=\"9\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8399\">\n\t\t\t\t\t\t\t<div class=\"plus-content-editor\" ><table><tbody><tr><td>\u00a0<\/td><\/tr><tr><td><span style=\"color: #999999;\">Contacto de ventas<\/span><\/td><\/tr><tr><td>Orlando P\u00e9rez<\/td><\/tr><tr><td><a style=\"color: #2e3b56;\" href=\"mailto:operez@uavlatam.com\">operez@uavlatam.com<\/a><\/td><td><a style=\"color: #2e3b56;\" href=\"mailto:operez@uavlatam.com\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11369\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-envelope.png\" alt=\"\" width=\"20\" height=\"32\" \/><\/a><\/td><\/tr><tr><td><a style=\"color: #2e3b56;\" href=\"https:\/\/wa.me\/18092249000\" target=\"_blank;\">+1(809) 224 9000<\/a><\/td><td><a href=\"https:\/\/wa.me\/18092249000\" target=\"_blank;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11372 size-full\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-phone.png\" alt=\"\" width=\"20\" height=\"41\" \/><\/a><\/td><\/tr><tr><td>\u00a0<\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div> \n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div> \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-28616bf elementor-hidden-mobile\" data-id=\"28616bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4ba875 elementor-widget elementor-widget-shortcode\" data-id=\"d4ba875\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\n          \t<div class=\"wrap_svl_center\">\r\n\t<div class=\"wrap_svl_center_box\">\r\n\t<div class=\"wrap_svl\" id=\"body_drag_11255\">\r\n\t\t<div class=\"images_wrap\">\r\n\t\t<img decoding=\"async\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/02\/uavlatam-drone-mapa-latinoamerica-4-min.png\">\r\n\t\t<\/div>\t\r\n\t\t \t\t \t\t <div class=\"drag_element tips \" style=\"top:14.05%;left:59.04%;\" >\r\n\t\t \t<div class=\"point_style  ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;&lt;span class=&quot;close_ihp&quot;&gt;&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;&lt;p&gt;&lt;strong&gt;&lt;span style=&quot;color: #0270c9&quot;&gt;REP\u00daBLICA DOMINICANA&lt;\/span&gt;&lt;\/strong&gt;&lt;\/p&gt;\n&lt;p&gt;&lt;strong&gt;Contacto de ventas&lt;\/strong&gt;&lt;\/p&gt;\n&lt;p&gt;Orlando P\u00e9rez&lt;\/p&gt;\n&lt;p&gt;&lt;a href=&quot;mailto:operez@uavlatam.com&quot;&gt;&lt;img decoding=&quot;async&quot; class=&quot;alignnone wp-image-11506&quot; src=&quot;https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-envelope.png&quot; alt=&quot;&quot; width=&quot;18&quot; height=&quot;14&quot; \/&gt;&lt;\/a&gt; \u00a0&lt;a href=&quot;mailto:operez@uavlatam.com&quot;&gt;operez@uavlatam.com&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&lt;a href=&quot;https:\/\/wa.me\/18092249000&quot;&gt;&lt;img decoding=&quot;async&quot; class=&quot;alignnone wp-image-13371&quot; src=&quot;https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-icon-whatsapp-min.png&quot; alt=&quot;&quot; width=&quot;22&quot; height=&quot;20&quot; \/&gt;&lt;\/a&gt; \u00a0&lt;a href=&quot;https:\/\/wa.me\/18092249000&quot; target=&quot;_blank&quot; rel=&quot;noopener&quot;&gt;+1(809) 224 9000&lt;\/a&gt;&lt;\/p&gt;\n&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-25px;left:-25px;height:50px;width:50px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/02\/ico-republica-dominicana-min.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-25px;left:-25px\">\r\n\t\t\t \t\t\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t <div class=\"drag_element tips \" style=\"top:15.23%;left:13.22%;\" >\r\n\t\t \t<div class=\"point_style  ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;&lt;span class=&quot;close_ihp&quot;&gt;&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;&lt;p&gt;&lt;strong&gt;&lt;span style=&quot;color: #0270c9&quot;&gt;M\u00c9XICO&lt;\/span&gt;&lt;\/strong&gt;&lt;\/p&gt;\n&lt;p&gt;&lt;strong&gt;Contacto de ventas&lt;\/strong&gt;&lt;\/p&gt;\n&lt;p&gt;Alicia Hern\u00e1ndez&lt;\/p&gt;\n&lt;p&gt;&lt;a href=&quot;mailto:ahernandez@uavlatam.com&quot;&gt;&lt;img decoding=&quot;async&quot; class=&quot;alignnone wp-image-11506&quot; src=&quot;https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-envelope.png&quot; alt=&quot;&quot; width=&quot;18&quot; height=&quot;14&quot; \/&gt;ahernandez&lt;\/a&gt;&lt;a href=&quot;mailto:ahernandez@uavlatam.com&quot;&gt;@uavlatam.com&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&lt;a href=&quot;https:\/\/wa.me\/5214423787054&quot;&gt;&lt;img decoding=&quot;async&quot; class=&quot;alignnone wp-image-13371&quot; src=&quot;https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-icon-whatsapp-min.png&quot; alt=&quot;&quot; width=&quot;22&quot; height=&quot;20&quot; \/&gt;&lt;\/a&gt; \u00a0&lt;a href=&quot;https:\/\/wa.me\/524423787054&quot; target=&quot;_blank&quot; rel=&quot;noopener&quot;&gt;+52 442 378 7054&lt;\/a&gt;&lt;\/p&gt;\n&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-25px;left:-25px;height:50px;width:50px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/02\/ico-mexico-min.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-25px;left:-25px\">\r\n\t\t\t \t\t\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t <div class=\"drag_element tips \" style=\"top:51.06%;left:77.97%;\" >\r\n\t\t \t<div class=\"point_style  ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;&lt;span class=&quot;close_ihp&quot;&gt;&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;&lt;p&gt;&lt;strong&gt;&lt;span style=&quot;color: #0270c9&quot;&gt;BRASIL&lt;\/span&gt;&lt;\/strong&gt;&lt;\/p&gt;\n&lt;p&gt;&lt;strong&gt;Contacto de ventas&lt;\/strong&gt;&lt;\/p&gt;\n&lt;p&gt;Guillermo Bergelund&lt;\/p&gt;\n&lt;p&gt;&lt;a href=&quot;mailto:mquiros@uavlatam.com&quot;&gt;&lt;img decoding=&quot;async&quot; class=&quot;alignnone wp-image-11506&quot; src=&quot;https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-envelope.png&quot; alt=&quot;&quot; width=&quot;18&quot; height=&quot;14&quot; \/&gt;&lt;\/a&gt; \u00a0&lt;a href=&quot;mailto:gbergelund@uavlatam.com&quot;&gt;gbergelund@uavlatam.com&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&lt;a href=&quot;https:\/\/wa.me\/56992221540&quot;&gt;&lt;img decoding=&quot;async&quot; class=&quot;alignnone wp-image-13371&quot; src=&quot;https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-icon-whatsapp-min.png&quot; alt=&quot;&quot; width=&quot;22&quot; height=&quot;20&quot; \/&gt;&lt;\/a&gt; \u00a0&lt;a href=&quot;https:\/\/wa.me\/51989256123&quot; target=&quot;_blank&quot; rel=&quot;noopener&quot;&gt;+51989256123&lt;\/a&gt;&lt;\/p&gt;\n&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-25px;left:-25px;height:50px;width:50px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/02\/ico-brasil-min.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-25px;left:-25px\">\r\n\t\t\t \t\t\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t <div class=\"drag_element tips \" style=\"top:70.54%;left:49.05%;\" >\r\n\t\t \t<div class=\"point_style  ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;&lt;span class=&quot;close_ihp&quot;&gt;&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;&lt;p&gt;&lt;strong&gt;&lt;span style=&quot;color: #0270c9&quot;&gt;CHILE&lt;\/span&gt;&lt;\/strong&gt;&lt;\/p&gt;\n&lt;p&gt;&lt;strong&gt;Contacto de ventas&lt;\/strong&gt;&lt;\/p&gt;\n&lt;p&gt;Mar\u00eda Beatriz Quiros&lt;\/p&gt;\n&lt;p&gt;&lt;a href=&quot;mailto:mquiros@uavlatam.com&quot;&gt;&lt;img decoding=&quot;async&quot; class=&quot;alignnone wp-image-11506&quot; src=&quot;https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-envelope.png&quot; alt=&quot;&quot; width=&quot;18&quot; height=&quot;14&quot; \/&gt;&lt;\/a&gt; \u00a0&lt;a href=&quot;mbquiros@uavlatam.com&quot;&gt;mbquiros@uavlatam.com&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&lt;a href=&quot;https:\/\/wa.me\/56992221540&quot;&gt;&lt;img decoding=&quot;async&quot; class=&quot;alignnone wp-image-13371&quot; src=&quot;https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-icon-whatsapp-min.png&quot; alt=&quot;&quot; width=&quot;22&quot; height=&quot;20&quot; \/&gt;&lt;\/a&gt; \u00a0&lt;a href=&quot;https:\/\/wa.me\/56998747462&quot; target=&quot;_blank&quot; rel=&quot;noopener&quot;&gt;+56 9 98747462&lt;\/a&gt;&lt;\/p&gt;\n&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-25px;left:-25px;height:50px;width:50px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/02\/ico-chile-min.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-25px;left:-25px\">\r\n\t\t\t \t\t\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t <div class=\"drag_element tips \" style=\"top:30.36%;left:53.35%;\" >\r\n\t\t \t<div class=\"point_style  ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;&lt;span class=&quot;close_ihp&quot;&gt;&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;&lt;p&gt;&lt;strong&gt;&lt;span style=&quot;color: #0270c9&quot;&gt;COLOMBIA&lt;\/span&gt;&lt;\/strong&gt;&lt;\/p&gt;\n&lt;p&gt;&lt;strong&gt;Contacto de ventas&lt;\/strong&gt;&lt;\/p&gt;\n&lt;p&gt;Rodrigo Medina&lt;\/p&gt;\n&lt;p&gt;&lt;a href=&quot;mailto:rmedina@uavlatam.com&quot;&gt;&lt;img decoding=&quot;async&quot; class=&quot;alignnone wp-image-11506&quot; src=&quot;https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-envelope.png&quot; alt=&quot;&quot; width=&quot;18&quot; height=&quot;14&quot; \/&gt;&lt;\/a&gt; \u00a0&lt;a href=&quot;mailto:rmedina@uavlatam.com&quot;&gt;rmedina@uavlatam.com&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&lt;a href=&quot;https:\/\/wa.me\/573144391738&quot;&gt;&lt;img decoding=&quot;async&quot; class=&quot;alignnone wp-image-13371&quot; src=&quot;https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-icon-whatsapp-min.png&quot; alt=&quot;&quot; width=&quot;22&quot; height=&quot;20&quot; \/&gt;&lt;\/a&gt; \u00a0&lt;a href=&quot;https:\/\/wa.me\/573144391738&quot; target=&quot;_blank&quot; rel=&quot;noopener&quot;&gt;+57 314 4391 738&lt;\/a&gt;&lt;\/p&gt;\n&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-25px;left:-25px;height:50px;width:50px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/02\/ico-colombia-min.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-25px;left:-25px\">\r\n\t\t\t \t\t\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t <div class=\"drag_element tips \" style=\"top:26.59%;left:33.05%;\" >\r\n\t\t \t<div class=\"point_style  ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;&lt;span class=&quot;close_ihp&quot;&gt;&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;&lt;p&gt;&lt;strong&gt;&lt;span style=&quot;color: #0270c9&quot;&gt;COSTA RICA&lt;\/span&gt;&lt;\/strong&gt;&lt;\/p&gt;\n&lt;p&gt;&lt;strong&gt;Contacto de ventas&lt;\/strong&gt;&lt;\/p&gt;\n&lt;p&gt;Francisco Fallas&lt;\/p&gt;\n&lt;p&gt;&lt;a href=&quot;mailto:ffallas@uavlatam.com&quot;&gt;&lt;img decoding=&quot;async&quot; class=&quot;alignnone wp-image-11506&quot; src=&quot;https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-envelope.png&quot; alt=&quot;&quot; width=&quot;18&quot; height=&quot;14&quot; \/&gt;&lt;\/a&gt; \u00a0&lt;a href=&quot;mailto:ffallas@uavlatam.com&quot;&gt;ffallas@uavlatam.com&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&lt;a href=&quot;https:\/\/wa.me\/50683853934&quot;&gt;&lt;img decoding=&quot;async&quot; class=&quot;alignnone wp-image-13371&quot; src=&quot;https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-icon-whatsapp-min.png&quot; alt=&quot;&quot; width=&quot;22&quot; height=&quot;20&quot; \/&gt;&lt;\/a&gt; \u00a0&lt;a href=&quot;https:\/\/wa.me\/50683853934&quot; target=&quot;_blank&quot; rel=&quot;noopener&quot;&gt;+506 8385-3934&lt;\/a&gt;&lt;\/p&gt;\n&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-25px;left:-25px;height:50px;width:50px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/02\/ico-costa-rica-min.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-25px;left:-25px\">\r\n\t\t\t \t\t\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t <div class=\"drag_element tips \" style=\"top:24.62%;left:45.44%;\" >\r\n\t\t \t<div class=\"point_style  ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;&lt;span class=&quot;close_ihp&quot;&gt;&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;&lt;p&gt;&lt;strong&gt;&lt;span style=&quot;color: #0270c9&quot;&gt;PANAM\u00c1&lt;\/span&gt;&lt;\/strong&gt;&lt;\/p&gt;\n&lt;p&gt;&lt;strong&gt;Contacto de ventas&lt;\/strong&gt;&lt;\/p&gt;\n&lt;p&gt;Eduardo L\u00f3pez&lt;\/p&gt;\n&lt;p&gt;&lt;a href=&quot;mailto:elopez@uavlatam.com&quot;&gt;&lt;img decoding=&quot;async&quot; class=&quot;alignnone wp-image-11506&quot; src=&quot;https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-envelope.png&quot; alt=&quot;&quot; width=&quot;18&quot; height=&quot;14&quot; \/&gt;&lt;\/a&gt; \u00a0&lt;a href=&quot;mailto:elopez@uavlatam.com&quot;&gt;elopez@uavlatam.com&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&lt;a href=&quot;https:\/\/wa.me\/50766196456&quot;&gt;&lt;img decoding=&quot;async&quot; class=&quot;alignnone wp-image-13371&quot; src=&quot;https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-icon-whatsapp-min.png&quot; alt=&quot;&quot; width=&quot;22&quot; height=&quot;20&quot; \/&gt;&lt;\/a&gt; \u00a0&lt;a href=&quot;https:\/\/wa.me\/50766196456&quot; target=&quot;_blank&quot; rel=&quot;noopener&quot;&gt;+507 66196456&lt;\/a&gt;&lt;\/p&gt;\n&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-25px;left:-25px;height:50px;width:50px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/02\/ico-panama-min.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-25px;left:-25px\">\r\n\t\t\t \t\t\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t <div class=\"drag_element tips \" style=\"top:80.18%;left:62.79%;\" >\r\n\t\t \t<div class=\"point_style  ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;&lt;span class=&quot;close_ihp&quot;&gt;&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;&lt;p&gt;&lt;strong&gt;&lt;span style=&quot;color: #0270c9&quot;&gt;ARGENTINA&lt;\/span&gt;&lt;\/strong&gt;&lt;\/p&gt;\n&lt;p&gt;&lt;strong&gt;Contacto de ventas&lt;\/strong&gt;&lt;\/p&gt;\n&lt;p&gt;Guillermo Bergelund&lt;\/p&gt;\n&lt;p&gt;&lt;a href=&quot;mailto:mquiros@uavlatam.com&quot;&gt;&lt;img decoding=&quot;async&quot; class=&quot;alignnone wp-image-11506&quot; src=&quot;https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-envelope.png&quot; alt=&quot;&quot; width=&quot;18&quot; height=&quot;14&quot; \/&gt;&lt;\/a&gt; \u00a0&lt;a href=&quot;mailto:gbergelund@uavlatam.com&quot;&gt;gbergelund@uavlatam.com&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&lt;a href=&quot;https:\/\/wa.me\/56992221540&quot;&gt;&lt;img decoding=&quot;async&quot; class=&quot;alignnone wp-image-13371&quot; src=&quot;https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-icon-whatsapp-min.png&quot; alt=&quot;&quot; width=&quot;22&quot; height=&quot;20&quot; \/&gt;&lt;\/a&gt; \u00a0&lt;a href=&quot;https:\/\/wa.me\/51989256123&quot; target=&quot;_blank&quot; rel=&quot;noopener&quot;&gt;+51989256123&lt;\/a&gt;&lt;\/p&gt;\n&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-25px;left:-25px;height:50px;width:50px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/02\/ico-argentina-min.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-25px;left:-25px\">\r\n\t\t\t \t\t\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t <div class=\"drag_element tips \" style=\"top:52.12%;left:45.27%;\" >\r\n\t\t \t<div class=\"point_style  ihotspot_tooltop_html\" data-placement=\"n\" data-html=\"\t\t \t\t\t                  &lt;div class=&quot;box_view_html&quot;&gt;&lt;span class=&quot;close_ihp&quot;&gt;&lt;svg version=&quot;1.1&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot; xmlns:xlink=&quot;http:\/\/www.w3.org\/1999\/xlink&quot; x=&quot;0px&quot; y=&quot;0px&quot; viewBox=&quot;0 0 1000 1000&quot; enable-background=&quot;new 0 0 1000 1000&quot; xml:space=&quot;preserve&quot;&gt;&lt;g&gt;&lt;path d=&quot;M153.7,153.7C57.9,249.5,10,365.3,10,499c0,135.7,47.9,251.5,143.7,347.3l0,0C249.5,942.1,363.3,990,499,990c135.7,0,251.5-47.9,347.3-143.7C942.1,750.5,990,634.7,990,499c0-135.7-47.9-249.5-143.7-345.3l0,0C750.5,57.9,634.7,10,499,10C365.3,10,249.5,57.9,153.7,153.7z M209.6,211.6l2-2C289.4,129.7,387.2,89.8,499,89.8c113.8,0,209.6,39.9,291.4,121.8c79.8,77.8,119.8,175.6,119.8,287.4c0,113.8-39.9,209.6-119.8,291.4C708.6,870.3,612.8,910.2,499,910.2c-111.8,0-209.6-39.9-287.4-119.8C129.8,708.6,89.8,612.8,89.8,499C89.8,387.2,129.8,289.4,209.6,211.6z&quot;\/&gt;&lt;path d=&quot;M293.4,331.3c0,12,4,22,12,29.9L443.1,497L305.4,632.7c-8,8-12,18-12,29.9c0,10,4,18,12,26c8,8,18,12,28,12c12,0,20-4,27.9-10L499,552.9l135.7,137.7c8,6,16,10,28,10c12,0,21.9-4,27.9-10c8-8,12-18,12-28c0-12-4-21.9-12-29.9L554.9,497l135.7-135.7c8-8,12-18,12-27.9c0-12-4-22-12-29.9c-6-8-16-12-25.9-12c-12,0-21.9,4-29.9,12L499,441.1L363.3,303.4c-8-8-18-12-29.9-12c-10,0-20,4-28,12C297.4,311.4,293.4,321.4,293.4,331.3z&quot;\/&gt;&lt;\/g&gt;&lt;\/svg&gt;&lt;\/span&gt;&lt;p&gt;&lt;strong&gt;&lt;span style=&quot;color: #0270c9&quot;&gt;PER\u00da&lt;\/span&gt; &lt;\/strong&gt;&lt;\/p&gt;\n&lt;p&gt;&lt;strong&gt;Contacto de ventas&lt;\/strong&gt;&lt;\/p&gt;\n&lt;p&gt;Guillermo Bergelund&lt;\/p&gt;\n&lt;p&gt;&lt;a href=&quot;mailto:mquiros@uavlatam.com&quot;&gt;&lt;img decoding=&quot;async&quot; class=&quot;alignnone wp-image-11506&quot; src=&quot;https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/03\/uavlatam-drone-icon-envelope.png&quot; alt=&quot;&quot; width=&quot;18&quot; height=&quot;14&quot; \/&gt;&lt;\/a&gt; \u00a0&lt;a href=&quot;mailto:gbergelund@uavlatam.com&quot;&gt;gbergelund@uavlatam.com&lt;\/a&gt;&lt;\/p&gt;\n&lt;p&gt;&lt;a href=&quot;https:\/\/wa.me\/56992221540&quot;&gt;&lt;img decoding=&quot;async&quot; class=&quot;alignnone wp-image-13371&quot; src=&quot;https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-icon-whatsapp-min.png&quot; alt=&quot;&quot; width=&quot;22&quot; height=&quot;20&quot; \/&gt;&lt;\/a&gt; \u00a0&lt;a href=&quot;https:\/\/wa.me\/51989256123&quot; target=&quot;_blank&quot; rel=&quot;noopener&quot;&gt;+51989256123&lt;\/a&gt;&lt;\/p&gt;\n&lt;\/div&gt;\r\n\t\t\t \t\t \t\t \">\r\n\t\t \t\t\t\t\t \t\t\t\t\t \t\t\t<div class=\"pins_animation ihotspot_pulse\" style=\"top:-25px;left:-25px;height:50px;width:50px\"><\/div>\r\n\t\t\t \t\t\t\t\t \t\t<img decoding=\"async\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/02\/ico-peru-min.png\" class=\"pins_image ihotspot_hastooltop\" style=\"top:-25px;left:-25px\">\r\n\t\t\t \t\t\t\t \t\t\t\t \t<\/div>\r\n\t\t <\/div>\r\n\t\t \t\t \r\n\t\t  \t\t \t\r\n\t <\/div>\r\n\t <\/div>\r\n\t <\/div>\r\n\t\n        <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6b26ebe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6b26ebe\" data-element_type=\"section\" id=\"soluciones\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d041e59\" data-id=\"d041e59\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7043547 elementor-widget elementor-widget-heading\" data-id=\"7043547\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Solu\u00e7\u00f5es<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8596f19 elementor-widget elementor-widget-heading\" data-id=\"8596f19\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">tecnologia para\nopera\u00e7\u00f5es mais eficientes<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc54f62 elementor-widget elementor-widget-text-editor\" data-id=\"dc54f62\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Saiba como nossas solu\u00e7\u00f5es permitem melhorar suas opera\u00e7\u00f5es e processos, mesmo nos cen\u00e1rios e condi\u00e7\u00f5es mais complexos.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0528e1c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0528e1c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6bf839e\" data-id=\"6bf839e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ae5a06 elementor-view-framed elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"9ae5a06\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 607.51 638\"><defs><style>.cls-1{fill:#00d646;}.cls-2{fill:#051c2c;}<\/style><\/defs><g id=\"Capa_2\" data-name=\"Capa 2\"><g id=\"Capa_1-2\" data-name=\"Capa 1\"><path class=\"cls-1\" d=\"M255.28,577.8a48.48,48.48,0,1,0,48.48-48.48,48.47,48.47,0,0,0-48.48,48.48Z\"><\/path><path class=\"cls-2\" d=\"M144.51,329.42H249.15c3.39,10.43,12.38,18,22.94,18h63.2c10.55,0,19.55-7.43,22.93-18H463a11.86,11.86,0,1,0,0-23.71H347.8a11.9,11.9,0,0,0-11.86,11.86v2.73a5.07,5.07,0,0,1-1,3.39H272.61a5,5,0,0,1-1.17-3.39v-2.73a11.91,11.91,0,0,0-11.86-11.86H144.51a11.86,11.86,0,0,0,0,23.71Z\"><\/path><path class=\"cls-2\" d=\"M60.07,410.09H547.43a54.94,54.94,0,0,0,54.86-54.86V326.56a11.9,11.9,0,0,0-11.85-11.86H558.51V35.18C556.56,15.12,540.4,0,520.85,0H85.09A36.37,36.37,0,0,0,48.74,36.36V314.83H16.94A11.9,11.9,0,0,0,5.08,326.69v28.67a55,55,0,0,0,55,54.73Zm-31.4-71.67H60.46a11.91,11.91,0,0,0,11.86-11.86V36.36A12.79,12.79,0,0,1,85.09,23.59H521c7,0,13.16,5.86,14.07,13.42V326.56a11.91,11.91,0,0,0,11.86,11.86h31.8v16.81a31.36,31.36,0,0,1-31.28,31.27H60.07A31.36,31.36,0,0,1,28.8,355.23V338.42Zm567,251.1a11.86,11.86,0,1,0,0-23.71H362.91a60.3,60.3,0,0,0-47.3-47.3V463.64a11.86,11.86,0,0,0-23.71,0v54.87a60.31,60.31,0,0,0-47.31,47.3H11.86a11.86,11.86,0,1,0,0,23.71H244.72a60.34,60.34,0,0,0,118.32,0Zm-291.9,24.89a36.62,36.62,0,1,1,36.62-36.61,36.65,36.65,0,0,1-36.62,36.61Z\"><\/path><path class=\"cls-1\" d=\"M243.74,205.83V127.54q0-6.11,2.78-9.15a9.28,9.28,0,0,1,7.18-3,9.61,9.61,0,0,1,7.36,3q2.81,3,2.81,9.18v78.29q0,6.16-2.81,9.21a9.53,9.53,0,0,1-7.36,3.05,9.25,9.25,0,0,1-7.15-3.08Q243.75,211.92,243.74,205.83Z\"><\/path><path class=\"cls-1\" d=\"M350,205.15l-4.74-12.47h-40.4l-4.74,12.74q-2.79,7.46-4.75,10.07t-6.44,2.6a9.44,9.44,0,0,1-6.71-2.77,8.54,8.54,0,0,1-2.91-6.31,14.14,14.14,0,0,1,.67-4.2c.46-1.45,1.2-3.46,2.24-6l25.42-64.53q1.08-2.77,2.61-6.68a34.39,34.39,0,0,1,3.25-6.47,13.2,13.2,0,0,1,4.54-4.17,14,14,0,0,1,6.95-1.59,14.13,14.13,0,0,1,7,1.59,13.6,13.6,0,0,1,4.54,4.1,29.11,29.11,0,0,1,2.91,5.39q1.18,2.88,3,7.7l26,64.12q3,7.32,3.05,10.64a8.8,8.8,0,0,1-2.88,6.33,9.48,9.48,0,0,1-6.95,2.88,9.09,9.09,0,0,1-4.07-.84,8.2,8.2,0,0,1-2.84-2.31,21,21,0,0,1-2.48-4.47Q350.9,207.46,350,205.15ZM310.1,177.56h29.68l-15-41Z\"><\/path><\/g><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-366454e elementor-widget elementor-widget-heading\" data-id=\"366454e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">An\u00e1lise de dados com IA<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc3ec53 elementor-widget elementor-widget-text-editor\" data-id=\"dc3ec53\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Transforme seus dados em informa\u00e7\u00f5es valiosas. Obtenha insights precisos para decis\u00f5es mais oportunas e acertadas.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69ec958 elementor-align-justify elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"69ec958\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contactanos\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mais informa\u00e7\u00e3o<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-dbd4e12\" data-id=\"dbd4e12\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0d2f4b elementor-view-framed elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"e0d2f4b\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1024 638\"><defs><style>.cls-1{fill:#00d646;}.cls-2{fill:#fff;}.cls-3{fill:#051c2c;}<\/style><\/defs><g id=\"Capa_2\" data-name=\"Capa 2\"><g id=\"Capa_1-2\" data-name=\"Capa 1\"><path class=\"cls-1\" d=\"M512,626.2a79.47,79.47,0,0,1-79.4-79.4V467.4H591.4v79.4A79.47,79.47,0,0,1,512,626.2Z\"><\/path><path class=\"cls-2\" d=\"M512,581.6a34.8,34.8,0,1,1,34.8-34.8A34.83,34.83,0,0,1,512,581.6Z\"><\/path><path class=\"cls-3\" d=\"M205.2,60H11.8a11.8,11.8,0,0,1,0-23.6H205.2a11.8,11.8,0,1,1,0,23.6Zm807,0H818.8a11.8,11.8,0,1,1,0-23.6h193.4A11.82,11.82,0,0,1,1024,48.2,11.7,11.7,0,0,1,1012.2,60Z\"><\/path><path class=\"cls-3\" d=\"M132.8,97.8H80.6A11.82,11.82,0,0,1,68.8,86V37.8a37.8,37.8,0,0,1,75.6,0V86a11.78,11.78,0,0,1-11.6,11.8ZM92.4,74.2H121V37.8a14.4,14.4,0,0,0-28.8,0V74.2Z\"><\/path><path class=\"cls-3\" d=\"M566.4,326.8H457.6a63,63,0,0,1-63-63V68.6a63,63,0,0,1,63-63H566.4a63,63,0,0,1,63,63V263.8A63,63,0,0,1,566.4,326.8ZM457.6,29A39.69,39.69,0,0,0,418,68.6V263.8a39.69,39.69,0,0,0,39.6,39.6H566.4A39.69,39.69,0,0,0,606,263.8V68.6A39.69,39.69,0,0,0,566.4,29Z\"><\/path><path class=\"cls-3\" d=\"M406.4,200.4H153.8A11.82,11.82,0,0,1,142,188.6V117.2a11.82,11.82,0,0,1,11.8-11.8H406.4a11.82,11.82,0,0,1,11.8,11.8v71.4a12,12,0,0,1-11.8,11.8ZM165.4,177H394.6V129H165.4Z\"><\/path><path class=\"cls-3\" d=\"M406.4,166.2H153.8A11.82,11.82,0,0,1,142,154.4a11.7,11.7,0,0,1,11.8-11.8H406.4a11.8,11.8,0,1,1,0,23.6Zm124,20H493.6a47.8,47.8,0,0,1-47.8-47.8V17.2A11.82,11.82,0,0,1,457.6,5.4H566.4a11.82,11.82,0,0,1,11.8,11.8V138.4A47.93,47.93,0,0,1,530.4,186.2ZM469.4,29V138.4a24.5,24.5,0,0,0,24.4,24.4h36.8A24.5,24.5,0,0,0,555,138.4V29ZM106.6,324.2a30,30,0,0,1-30-30V219.6a11.87,11.87,0,0,1,5.2-9.8,11.36,11.36,0,0,1,11-1,36.11,36.11,0,0,0,27.4,0,11.36,11.36,0,0,1,11,1,11.87,11.87,0,0,1,5.2,9.8v74.6C136.8,310.6,123.2,324.2,106.6,324.2Zm-6.4-89.8V294a6.6,6.6,0,0,0,13.2,0V234.4A48.62,48.62,0,0,1,100.2,234.4Z\"><\/path><path class=\"cls-3\" d=\"M106.6,234.8A58.9,58.9,0,0,1,47.8,176V85.8A11.82,11.82,0,0,1,59.6,74h94a11.82,11.82,0,0,1,11.8,11.8V176A58.9,58.9,0,0,1,106.6,234.8ZM71.4,97.8v78.4A35.3,35.3,0,1,0,142,176V97.6H71.4ZM870.2,200.4H617.6a11.82,11.82,0,0,1-11.8-11.8V117.2a11.82,11.82,0,0,1,11.8-11.8H870.2A11.82,11.82,0,0,1,882,117.2v71.4a11.7,11.7,0,0,1-11.8,11.8ZM629.4,177H858.6V129H629.4Zm314-79.2H891.2A11.82,11.82,0,0,1,879.4,86V37.8a37.8,37.8,0,1,1,75.6,0V86A11.78,11.78,0,0,1,943.4,97.8ZM903,74.2h28.6V37.8a14.4,14.4,0,1,0-28.8,0V74.2Z\"><\/path><path class=\"cls-3\" d=\"M870.2,166.2H617.6a11.82,11.82,0,0,1-11.8-11.8,11.7,11.7,0,0,1,11.8-11.8H870.2A11.82,11.82,0,0,1,882,154.4a11.7,11.7,0,0,1-11.8,11.8Zm47.2,158a30,30,0,0,1-30-30V219.6a11.87,11.87,0,0,1,5.2-9.8,11.36,11.36,0,0,1,11-1,36.11,36.11,0,0,0,27.4,0,11.36,11.36,0,0,1,11,1,11.87,11.87,0,0,1,5.2,9.8v74.6a29.92,29.92,0,0,1-29.8,30Zm-6.6-89.8V294a6.6,6.6,0,0,0,13.2,0V234.4a48.62,48.62,0,0,1-13.2,0Z\"><\/path><path class=\"cls-3\" d=\"M917.4,234.8A58.9,58.9,0,0,1,858.6,176V85.8A11.82,11.82,0,0,1,870.4,74h94a11.82,11.82,0,0,1,11.8,11.8V176C976,208.4,949.8,234.8,917.4,234.8ZM882,97.8v78.4a35.4,35.4,0,1,0,70.8,0V97.8Zm-325.6,265H467.6A11.82,11.82,0,0,1,455.8,351V315a11.82,11.82,0,0,1,11.8-11.8h88.8A11.82,11.82,0,0,1,568.2,315v36A11.82,11.82,0,0,1,556.4,362.8Zm-77-23.4h65.4V326.8H479.4v12.6Z\"><\/path><path class=\"cls-3\" d=\"M529.8,434.2H494.2a11.82,11.82,0,0,1-11.8-11.8V351.2a11.82,11.82,0,0,1,11.8-11.8h35.6a11.82,11.82,0,0,1,11.8,11.8v71.2A12.09,12.09,0,0,1,529.8,434.2ZM506,410.6h12V362.8H506ZM459.8,277.2a30.4,30.4,0,1,1,30.4-30.4A30.39,30.39,0,0,1,459.8,277.2Zm0-37.2a6.8,6.8,0,1,0,6.8,6.8A6.74,6.74,0,0,0,459.8,240Zm104.4,37.2a30.4,30.4,0,1,1,30.4-30.4A30.39,30.39,0,0,1,564.2,277.2Zm0-37.2a6.8,6.8,0,1,0,6.8,6.8A6.62,6.62,0,0,0,564.2,240ZM512,638a91.29,91.29,0,0,1-91.2-91.2V467.4a11.82,11.82,0,0,1,11.8-11.8H591.4a11.82,11.82,0,0,1,11.8,11.8v79.4A91.42,91.42,0,0,1,512,638ZM444.4,479.2v67.6a67.6,67.6,0,0,0,135.2,0V479.2Z\"><\/path><path class=\"cls-3\" d=\"M512,593.2a46.4,46.4,0,1,1,46.4-46.4A46.43,46.43,0,0,1,512,593.2Zm0-69.4a23,23,0,1,0,23,23A23.13,23.13,0,0,0,512,523.8Z\"><\/path><path class=\"cls-3\" d=\"M595.2,479.2H428.8a34.2,34.2,0,0,1,0-68.4H595.2a34.2,34.2,0,0,1,0,68.4Zm-166.4-45a10.8,10.8,0,1,0,0,21.6H595.2a10.8,10.8,0,0,0,0-21.6Z\"><\/path><\/g><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72f11e8 elementor-widget elementor-widget-heading\" data-id=\"72f11e8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">seguran\u00e7a e defesa<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39fb203 elementor-widget elementor-widget-text-editor\" data-id=\"39fb203\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Proteja seus ativos e \u00e1reas de interesse, tornando seus espa\u00e7os aqu\u00e1ticos e terrestres mais seguros e controlados.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-066f3c2 elementor-align-justify elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"066f3c2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contactanos\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Transforme Seu Neg\u00f3cio<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-36edb8e\" data-id=\"36edb8e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-647e7a1 elementor-view-framed elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"647e7a1\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1024 681\"><defs><style>.cls-1{fill:#00d646;}.cls-2{fill:#051c2c;}<\/style><\/defs><g id=\"Capa_2\" data-name=\"Capa 2\"><g id=\"Capa_1-2\" data-name=\"Capa 1\"><path class=\"cls-1\" d=\"M406.4,458H617.6V669.2H406.4Z\"><\/path><path class=\"cls-2\" d=\"M205.2,60.2H11.8a11.8,11.8,0,0,1,0-23.6H205.2A11.82,11.82,0,0,1,217,48.4,12,12,0,0,1,205.2,60.2Zm807,0H818.8a11.8,11.8,0,1,1,0-23.6h193.4a11.8,11.8,0,0,1,0,23.6Z\"><\/path><path class=\"cls-2\" d=\"M132.8,97.8H80.6A11.82,11.82,0,0,1,68.8,86V37.8a37.8,37.8,0,0,1,75.6,0V86a11.65,11.65,0,0,1-11.6,11.8ZM92.4,74.4H121V38a14.4,14.4,0,0,0-28.8,0V74.4Z\"><\/path><path class=\"cls-2\" d=\"M566.4,327H457.6a63,63,0,0,1-63-63V68.6a63,63,0,0,1,63-63H566.4a63,63,0,0,1,63,63V263.8a63,63,0,0,1-63,63.2ZM457.6,29.2A39.69,39.69,0,0,0,418,68.8V264a39.69,39.69,0,0,0,39.6,39.6H566.4A39.69,39.69,0,0,0,606,264V68.6A39.69,39.69,0,0,0,566.4,29H457.6Z\"><\/path><path class=\"cls-2\" d=\"M406.4,200.6H153.8A11.82,11.82,0,0,1,142,188.8V117.4a11.82,11.82,0,0,1,11.8-11.8H406.4a11.82,11.82,0,0,1,11.8,11.8v71.4a12,12,0,0,1-11.8,11.8Zm-241-23.4H394.6v-48H165.4Z\"><\/path><path class=\"cls-2\" d=\"M406.4,166.4H153.8A11.82,11.82,0,0,1,142,154.6a11.7,11.7,0,0,1,11.8-11.8H406.4a11.8,11.8,0,1,1,0,23.6Zm124,20H493.6a47.8,47.8,0,0,1-47.8-47.8V17.4A11.82,11.82,0,0,1,457.6,5.6H566.4a11.82,11.82,0,0,1,11.8,11.8V138.6A47.93,47.93,0,0,1,530.4,186.4Zm-61-157.2V138.6A24.5,24.5,0,0,0,493.8,163h36.8A24.5,24.5,0,0,0,555,138.6V29.2Zm-362.8,295a30,30,0,0,1-30-30V219.6a11.87,11.87,0,0,1,5.2-9.8,11.36,11.36,0,0,1,11-1,36.11,36.11,0,0,0,27.4,0,11.36,11.36,0,0,1,11,1,11.87,11.87,0,0,1,5.2,9.8v74.6C136.8,310.8,123.2,324.2,106.6,324.2Zm-6.4-89.6v59.6a6.6,6.6,0,0,0,13.2,0V234.6A72.74,72.74,0,0,1,100.2,234.6Z\"><\/path><path class=\"cls-2\" d=\"M106.6,235A58.72,58.72,0,0,1,48,176.2V86A11.82,11.82,0,0,1,59.8,74.2h94A11.82,11.82,0,0,1,165.6,86v90.2a59.2,59.2,0,0,1-59,58.8ZM71.4,97.8v78.4a35.3,35.3,0,1,0,70.6,0V97.8ZM870.2,200.6H617.6a11.82,11.82,0,0,1-11.8-11.8V117.4a11.82,11.82,0,0,1,11.8-11.8H870.2A11.82,11.82,0,0,1,882,117.4v71.4a11.7,11.7,0,0,1-11.8,11.8ZM629.4,177.2H858.6v-48H629.4Zm314-79.4H891.2A11.82,11.82,0,0,1,879.4,86V37.8a37.8,37.8,0,1,1,75.6,0V86A11.65,11.65,0,0,1,943.4,97.8ZM903,74.4h28.6V38a14.4,14.4,0,1,0-28.8,0V74.4Z\"><\/path><path class=\"cls-2\" d=\"M870.2,166.4H617.6a11.82,11.82,0,0,1-11.8-11.8,11.7,11.7,0,0,1,11.8-11.8H870.2A11.82,11.82,0,0,1,882,154.6a11.7,11.7,0,0,1-11.8,11.8Zm47.2,157.8a30,30,0,0,1-30-30V219.6a11.87,11.87,0,0,1,5.2-9.8,11.36,11.36,0,0,1,11-1,36.11,36.11,0,0,0,27.4,0,11.36,11.36,0,0,1,11,1,11.87,11.87,0,0,1,5.2,9.8v74.6a29.79,29.79,0,0,1-29.8,30Zm-6.6-89.6v59.6a6.6,6.6,0,0,0,13.2,0V234.6a72.74,72.74,0,0,1-13.2,0Z\"><\/path><path class=\"cls-2\" d=\"M917.4,235a58.9,58.9,0,0,1-58.8-58.8V86a11.82,11.82,0,0,1,11.8-11.8h94A11.82,11.82,0,0,1,976.2,86v90.2c-.2,32.4-26.4,58.8-58.8,58.8ZM882,97.8v78.4a35.4,35.4,0,1,0,70.8,0V97.8ZM556.4,363H467.6a11.82,11.82,0,0,1-11.8-11.8v-36a11.82,11.82,0,0,1,11.8-11.8h88.8a11.82,11.82,0,0,1,11.8,11.8v36A11.82,11.82,0,0,1,556.4,363Zm-77-23.4h65.4V327H479.4v12.6Z\"><\/path><path class=\"cls-2\" d=\"M529.8,434.2H494.2a11.82,11.82,0,0,1-11.8-11.8V351.2a11.82,11.82,0,0,1,11.8-11.8h35.6a11.82,11.82,0,0,1,11.8,11.8v71.2A12,12,0,0,1,529.8,434.2ZM506,410.8h12V363H506Z\"><\/path><path class=\"cls-2\" d=\"M653.2,575.4H617.6a11.82,11.82,0,0,1-11.8-11.8v-94H418v94a11.82,11.82,0,0,1-11.8,11.8H370.6a11.82,11.82,0,0,1-11.8-11.8V422.4a11.82,11.82,0,0,1,11.8-11.8H653a11.82,11.82,0,0,1,11.8,11.8V563.6A11.65,11.65,0,0,1,653.2,575.4ZM629.4,552h12V434.2H382.6V552h12V458a11.82,11.82,0,0,1,11.8-11.8H617.6A11.82,11.82,0,0,1,629.4,458v94ZM459.8,277.4A30.4,30.4,0,1,1,490.2,247C490,263.6,476.4,277.4,459.8,277.4Zm0-37.4a6.8,6.8,0,1,0,6.8,6.8A6.87,6.87,0,0,0,459.8,240Zm104.4,37.4A30.4,30.4,0,1,1,594.6,247,30.39,30.39,0,0,1,564.2,277.4Zm0-37.4a6.8,6.8,0,1,0,6.8,6.8A6.74,6.74,0,0,0,564.2,240Z\"><\/path><path class=\"cls-2\" d=\"M617.6,681H406.4a11.82,11.82,0,0,1-11.8-11.8V458a11.82,11.82,0,0,1,11.8-11.8H617.6A11.82,11.82,0,0,1,629.4,458V669.2A11.82,11.82,0,0,1,617.6,681ZM418,657.6H605.8V469.8H418Z\"><\/path><path class=\"cls-2\" d=\"M493.8,552.6a11.93,11.93,0,0,1-9.4-4.6l-15-19.6-15.2,19.4a11.68,11.68,0,0,1-18.4-14.4L460.4,502a11.5,11.5,0,0,1,18.4,0L503,533.6a11.58,11.58,0,0,1-2.2,16.4,10.16,10.16,0,0,1-7,2.6Z\"><\/path><path class=\"cls-2\" d=\"M469.6,594.6a11.82,11.82,0,0,1-11.8-11.8V509.2a11.82,11.82,0,0,1,11.8-11.8,11.7,11.7,0,0,1,11.8,11.8v73.6A12,12,0,0,1,469.6,594.6Zm109.4-42a11.93,11.93,0,0,1-9.4-4.6l-15-19.6-15.2,19.4A11.68,11.68,0,0,1,521,533.4L545.6,502a11.5,11.5,0,0,1,18.4,0l24.2,31.6A11.58,11.58,0,0,1,586,550a10.16,10.16,0,0,1-7,2.6Z\"><\/path><path class=\"cls-2\" d=\"M554.8,594.6A11.82,11.82,0,0,1,543,582.8V509.2a11.8,11.8,0,0,1,23.6,0v73.6A12,12,0,0,1,554.8,594.6Z\"><\/path><path class=\"cls-2\" d=\"M579,637.2H445a11.8,11.8,0,0,1,0-23.6H579a11.82,11.82,0,0,1,11.8,11.8A11.7,11.7,0,0,1,579,637.2Z\"><\/path><\/g><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f9c2f3 elementor-widget elementor-widget-heading\" data-id=\"1f9c2f3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">UAV CARGO<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ca22d3 elementor-widget elementor-widget-text-editor\" data-id=\"6ca22d3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Com um planejamento de voo inteligente, reduza o tempo e os custos de entrega de maneira eficiente e segura para sua organiza\u00e7\u00e3o.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1fcab5 elementor-align-justify elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"d1fcab5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contactanos\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Transforme Seu Neg\u00f3cio<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a7e190 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a7e190\" data-element_type=\"section\" id=\"sectores\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ccdce0\" data-id=\"6ccdce0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59ebacd elementor-widget elementor-widget-heading\" data-id=\"59ebacd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Trajet\u00f3ria e lideran\u00e7a<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c113c46 elementor-widget elementor-widget-heading\" data-id=\"c113c46\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">10+ anos de experi\u00eancia\nnos setores mais importantes<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dd70a6d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dd70a6d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-2618ab1\" data-id=\"2618ab1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17bfb3c elementor-widget elementor-widget-image\" data-id=\"17bfb3c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"250\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-mineria-min.jpg\" class=\"attachment-large size-large wp-image-13283\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-mineria-min.jpg 500w, https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-mineria-min-300x150.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f0a18e elementor-widget elementor-widget-heading\" data-id=\"7f0a18e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Minera\u00e7\u00e3o<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e0ce06 elementor-widget elementor-widget-text-editor\" data-id=\"7e0ce06\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Dados 3D geom\u00e9tricos e volum\u00e9tricos detalhados, bem como dados geoespaciais de alta resolu\u00e7\u00e3o.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8793135 elementor-widget elementor-widget-toggle\" data-id=\"8793135\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-toggle{text-align:start}.elementor-toggle .elementor-tab-title{font-weight:700;line-height:1;margin:0;padding:15px;border-bottom:1px solid #d5d8dc;cursor:pointer;outline:none}.elementor-toggle .elementor-tab-title .elementor-toggle-icon{display:inline-block;width:1em}.elementor-toggle .elementor-tab-title .elementor-toggle-icon svg{margin-inline-start:-5px;width:1em;height:1em}.elementor-toggle .elementor-tab-title .elementor-toggle-icon.elementor-toggle-icon-right{float:right;text-align:right}.elementor-toggle .elementor-tab-title .elementor-toggle-icon.elementor-toggle-icon-left{float:left;text-align:left}.elementor-toggle .elementor-tab-title .elementor-toggle-icon .elementor-toggle-icon-closed{display:block}.elementor-toggle .elementor-tab-title .elementor-toggle-icon .elementor-toggle-icon-opened{display:none}.elementor-toggle .elementor-tab-title.elementor-active{border-bottom:none}.elementor-toggle .elementor-tab-title.elementor-active .elementor-toggle-icon-closed{display:none}.elementor-toggle .elementor-tab-title.elementor-active .elementor-toggle-icon-opened{display:block}.elementor-toggle .elementor-tab-content{padding:15px;border-bottom:1px solid #d5d8dc;display:none}@media (max-width:767px){.elementor-toggle .elementor-tab-title{padding:12px}.elementor-toggle .elementor-tab-content{padding:12px 10px}}.e-con-inner>.elementor-widget-toggle,.e-con>.elementor-widget-toggle{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1421\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1421\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ver servi\u00e7os<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1421\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1421\"><ul>\n<li>Monitoramento de opera\u00e7\u00f5es<\/li>\n<li>I\u00e7amento de explosivos, controle<br \/>movimento material, dimens\u00e3o<br \/>encostas<\/li>\n<li>Modelagem de terreno para curvas de n\u00edvel Inspe\u00e7\u00e3o de infraestrutura<br \/>cr\u00edticos<\/li>\n<li>Monitoramento de bacias hidrogr\u00e1ficas<\/li>\n<li>c\u00e1lculo volum\u00e9trico<\/li>\n<li>Drone em uma caixa<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c3dafbf\" data-id=\"c3dafbf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-055984e elementor-widget elementor-widget-image\" data-id=\"055984e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"250\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-oil-gas-2-min.jpg\" class=\"attachment-large size-large wp-image-13280\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-oil-gas-2-min.jpg 500w, https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-oil-gas-2-min-300x150.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3995c6a elementor-widget elementor-widget-heading\" data-id=\"3995c6a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u00d3leo e g\u00e1s<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c915c33 elementor-widget elementor-widget-text-editor\" data-id=\"c915c33\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Identifique eros\u00f5es, trincas e desgastes em geral por meio de c\u00e2meras e sensores de alta resolu\u00e7\u00e3o.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25e9006 elementor-widget elementor-widget-toggle\" data-id=\"25e9006\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3971\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-3971\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ver servi\u00e7os<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3971\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-3971\"><ul>\n<li>Direito de passagem<\/li>\n<li>Inspe\u00e7\u00e3o de infraestruturas cr\u00edticas<\/li>\n<li>simula\u00e7\u00e3o de derramamento<\/li>\n<li>Topografia<\/li>\n<li>Invent\u00e1rio de ativos<\/li>\n<li>Inspe\u00e7\u00e3o de \u00e1reas contaminadas<\/li>\n<li>Identifica\u00e7\u00e3o de altera\u00e7\u00f5es no infracr\u00edtico<\/li>\n<li>Drone em uma caixa<\/li>\n<li>Levantamento fotogram\u00e9trico<\/li>\n<li>levantamento batim\u00e9trico<\/li>\n<li>Inspe\u00e7\u00f5es TEA de instala\u00e7\u00f5es de petr\u00f3leo<\/li>\n<li>Magnetografia<\/li>\n<li>Inspe\u00e7\u00e3o de G\u00e1s Metano<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-788203d\" data-id=\"788203d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-315fcc2 elementor-widget elementor-widget-image\" data-id=\"315fcc2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"250\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-agropecuario-min.jpg\" class=\"attachment-large size-large wp-image-13277\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-agropecuario-min.jpg 500w, https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-agropecuario-min-300x150.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ecc853d elementor-widget elementor-widget-heading\" data-id=\"ecc853d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Agr\u00edcola<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-acb733a elementor-widget elementor-widget-text-editor\" data-id=\"acb733a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nossas solu\u00e7\u00f5es apoiam os produtores da ind\u00fastria agr\u00edcola em diferentes est\u00e1gios do processo de produ\u00e7\u00e3o em seus esfor\u00e7os para melhorar a produtividade.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c9b12a elementor-widget elementor-widget-toggle\" data-id=\"2c9b12a\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4671\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-4671\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ver servi\u00e7os<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-4671\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-4671\"><ul>\n<li>Contagem de Plantas e Animais<\/li>\n<li>Estado fitossanit\u00e1rio<\/li>\n<li>\u00edndices multiespectrais<\/li>\n<li>Agricultura de precis\u00e3o<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-f542b5a\" data-id=\"f542b5a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e828d1 elementor-widget elementor-widget-image\" data-id=\"1e828d1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"250\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-defensa-seguridad-min.jpg\" class=\"attachment-large size-large wp-image-13274\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-defensa-seguridad-min.jpg 500w, https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-defensa-seguridad-min-300x150.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a10d2b0 elementor-widget elementor-widget-heading\" data-id=\"a10d2b0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Defesa e Seguran\u00e7a<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3398579 elementor-widget elementor-widget-text-editor\" data-id=\"3398579\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Maximize a capacidade de detectar indiv\u00edduos dentro de uma zona de perigo e avaliar danos e desastres.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-128de90 elementor-widget elementor-widget-toggle\" data-id=\"128de90\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1941\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1941\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ver servi\u00e7os<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1941\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1941\"><ul>\n<li>vigil\u00e2ncia perimetral<\/li>\n<li>Sistemas anti-drone (detec\u00e7\u00e3o e inibi\u00e7\u00e3o)<\/li>\n<li>Equipamento militar<\/li>\n<li>v\u00f4os de intelig\u00eancia<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9650ea6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9650ea6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d0a9390\" data-id=\"d0a9390\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6744bb8 elementor-widget elementor-widget-image\" data-id=\"6744bb8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"250\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-infraestructura-construccion-min.jpg\" class=\"attachment-large size-large wp-image-13271\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-infraestructura-construccion-min.jpg 500w, https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-infraestructura-construccion-min-300x150.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1731a45 elementor-widget elementor-widget-heading\" data-id=\"1731a45\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Infraestrutura, Constru\u00e7\u00e3o e Telecomunica\u00e7\u00f5es<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb84bc4 elementor-widget elementor-widget-text-editor\" data-id=\"eb84bc4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Avalie o estado t\u00e9cnico de sua infraestrutura e realize um processo de invent\u00e1rio.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d2b91c elementor-widget elementor-widget-toggle\" data-id=\"0d2b91c\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1381\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1381\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ver servi\u00e7os<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1381\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1381\"><ul>\n<li>inspe\u00e7\u00e3o de torre<br \/>telecomunica\u00e7\u00f5es (monitoramento de<br \/>obras de projeto<\/li>\n<li>Invent\u00e1rios e volumetria em mina a c\u00e9u aberto<\/li>\n<li>Modelagem digital de terreno para<br \/>curvas de n\u00edvel<\/li>\n<li>Monitoramento para quantificar o progresso dos processos erosivos<\/li>\n<li>Inspe\u00e7\u00e3o e localiza\u00e7\u00e3o de b\u00f3ias juntamente com disponibilidade de recursos<br \/>t\u00e9cnico<\/li>\n<li>An\u00e1lise t\u00e9cnica de plantas industriais<\/li>\n<li>Modelagem BIM de equipamentos e edif\u00edcios<\/li>\n<li>levantamento ortomosaico<\/li>\n<li>Levantamento batim\u00e9trico para gera\u00e7\u00e3o de modelos de volumes de dragagem fluvial e mar\u00edtima<\/li>\n<li>Identifica\u00e7\u00e3o de vest\u00edgios hist\u00f3ricos para modela\u00e7\u00e3o do terreno<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-fd08efe\" data-id=\"fd08efe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d65c79 elementor-widget elementor-widget-image\" data-id=\"0d65c79\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"250\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-energia-2-min.jpg\" class=\"attachment-large size-large wp-image-13268\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-energia-2-min.jpg 500w, https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-energia-2-min-300x150.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0062dda elementor-widget elementor-widget-heading\" data-id=\"0062dda\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Energia<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-272b816 elementor-widget elementor-widget-text-editor\" data-id=\"272b816\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Ajudamo-lo a reduzir o tempo de inspe\u00e7\u00e3o dos seus pain\u00e9is solares, torres de alta tens\u00e3o, parques e\u00f3licos, at\u00e9 70%.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9d9769 elementor-widget elementor-widget-toggle\" data-id=\"f9d9769\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2611\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2611\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ver servi\u00e7os<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2611\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2611\"><ul>\n<li>Inspe\u00e7\u00e3o e monitoramento de torres de alta tens\u00e3o e circuitos de distribui\u00e7\u00e3o el\u00e9trica<\/li>\n<li>Fiscaliza\u00e7\u00e3o e Monitoriza\u00e7\u00e3o de Parques Fotovoltaicos<\/li>\n<li>Inspe\u00e7\u00e3o e monitoramento de parques e\u00f3licos<\/li>\n<li>Acompanhamento de obras de projetos<\/li>\n<li>Inspe\u00e7\u00f5es termogr\u00e1ficas em pain\u00e9is solares<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-20c50fd\" data-id=\"20c50fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-614469c elementor-widget elementor-widget-image\" data-id=\"614469c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"250\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-gobierno-min.jpg\" class=\"attachment-large size-large wp-image-13265\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-gobierno-min.jpg 500w, https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-gobierno-min-300x150.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a342a1 elementor-widget elementor-widget-heading\" data-id=\"1a342a1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Governo<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9752a4d elementor-widget elementor-widget-text-editor\" data-id=\"9752a4d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Dispomos de um conjunto alargado de servi\u00e7os destinados a apoiar o setor p\u00fablico\/estatal em opera\u00e7\u00f5es SAR, vigil\u00e2ncia a\u00e9rea, controlo de fronteiras, cuidado de bens patrimoniais, entre outros.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fb0a82 elementor-widget elementor-widget-toggle\" data-id=\"6fb0a82\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1171\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1171\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ver servi\u00e7os<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1171\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1171\"><ul>\n<li>Cadastro<\/li>\n<li>inspe\u00e7\u00e3o de infraestrutura<br \/>cr\u00edticos<\/li>\n<li>Monitoramento de bacias hidrogr\u00e1ficas<\/li>\n<li>Monitoramento de vest\u00edgios arqueol\u00f3gicos<\/li>\n<li>Venda de equipamentos<\/li>\n<li>Apresenta\u00e7\u00e3o de projetos<br \/>modelo<\/li>\n<li>Preserva\u00e7\u00e3o e saneamento de \u00e1reas de valor ambiental<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-8ae1b5f\" data-id=\"8ae1b5f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1b3d9f elementor-widget elementor-widget-image\" data-id=\"f1b3d9f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"250\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-cargo-logistica-min.jpg\" class=\"attachment-large size-large wp-image-13262\" alt=\"\" srcset=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-cargo-logistica-min.jpg 500w, https:\/\/uavlatam.com\/wp-content\/uploads\/2023\/06\/uavlatam-drone-cargo-logistica-min-300x150.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66f3243 elementor-widget elementor-widget-heading\" data-id=\"66f3243\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Carga e logistica<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dace57 elementor-widget elementor-widget-text-editor\" data-id=\"6dace57\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Transporte a\u00e9reo r\u00e1pido de mercadorias de grande import\u00e2ncia para \u00e1reas urbanas congestionadas ou remotas sem transporte terrestre.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8b9963 elementor-widget elementor-widget-toggle\" data-id=\"a8b9963\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1761\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1761\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ver servi\u00e7os<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1761\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1761\"><ul>\n<li>Transporte de material m\u00e9dico<\/li>\n<li>log\u00edstica de transporte<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c313b7b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c313b7b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e7f2ad0\" data-id=\"e7f2ad0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1aeb73 elementor-widget elementor-widget-heading\" data-id=\"e1aeb73\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">O QUE FALAM NOSSOS CLIENTES<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0cee43e elementor-testimonial--skin-bubble elementor-testimonial--layout-image_inline elementor-testimonial--align-center elementor-arrows-yes elementor-pagination-type-bullets elementor-widget elementor-widget-testimonial-carousel\" data-id=\"0cee43e\" data-element_type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;3&quot;,&quot;slides_per_view_tablet&quot;:&quot;2&quot;,&quot;slides_per_view_mobile&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;slides_to_scroll_tablet&quot;:&quot;2&quot;,&quot;slides_to_scroll_mobile&quot;:&quot;1&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:8,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:8,&quot;sizes&quot;:[]},&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/uavlatam.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-carousel.min.css\">\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-main-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Complacido com o servi\u00e7o de captura e processamento de dados LIDAR requisitado \u00e0 empresa UAV LATAM para o projeto de amplia\u00e7\u00e3o da estrada no trajeto Santiago \u2013 San Jos\u00e9 De Las Matas. Os dados recebidos foram de grande utilidade para nossa equipe de design de vias.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Ing. Samuel \u00c1lvarez Ferm\u00edn<\/span><span class=\"elementor-testimonial__title\">Presidente de SMA & Asociados<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Valorizamos a oportunidade proporcionada pela UAV LATAM atrav\u00e9s de seus servi\u00e7os, nos dando acesso \u00e0 sua tecnologia de drones, software de processamento de dados e expertise na captura, processamento e an\u00e1lise de dados geoespaciais, assim como na aplica\u00e7\u00e3o de intelig\u00eancia artificial em projetos relacionados dos nossos associados.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">V\u00edctor Torres Rosa<\/span><span class=\"elementor-testimonial__title\">Presidente de ASODAGRIM<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Os levantamentos realizados pela empresa UAV LATAM tiveram um alto n\u00edvel de precis\u00e3o e qualidade. Sem d\u00favidas, evidencia-se uma not\u00e1vel experi\u00eancia na captura de imagens com tecnologia de drones e sensores visuais, al\u00e9m do processamento dos dados e sua an\u00e1lise.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Juan Jos\u00e9 Mercedes<\/span><span class=\"elementor-testimonial__title\">Coordenador CEPM<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"\u00c9 um prazer poder validar a presta\u00e7\u00e3o do servi\u00e7o, onde reconhecemos o esfor\u00e7o, a dedica\u00e7\u00e3o e o profissionalismo. Com certeza continuaremos a contratar seus servi\u00e7os. Recomendamos a excelente presta\u00e7\u00e3o e aten\u00e7\u00e3o do servi\u00e7o recebido pela UAV LATAM.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Helene Cent<\/span><span class=\"elementor-testimonial__title\">Santa Cecilia S.A.<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"A UAV LATAM prestou servi\u00e7os na \u00e1rea de topografia utilizando sensores LIDAR transportados por RPAS ou drones para o levantamento topogr\u00e1fico no setor de Pococ\u00ed, uma \u00e1rea com alta densidade de vegeta\u00e7\u00e3o e de dif\u00edcil acesso. Validamos a presta\u00e7\u00e3o do servi\u00e7o, especialmente os prazos e a qualidade dos dados que nos foram entregues.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Erick Soto<\/span><span class=\"elementor-testimonial__title\">Engenharia T&A CR S.A<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"O servi\u00e7o da UAV LATAM facilitou nosso trabalho de maneira exponencial, garantindo a seguran\u00e7a de nosso pessoal na mina, al\u00e9m de fornecer informa\u00e7\u00f5es de alto valor que nos permitiram economizar tempo de opera\u00e7\u00e3o.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Omar Zegarra<\/span><span class=\"elementor-testimonial__title\">Superintendente Shauindo<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e45a44 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e45a44\" data-element_type=\"section\" id=\"contactanos\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2b2f3de\" data-id=\"2b2f3de\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41d079c elementor-widget elementor-widget-heading\" data-id=\"41d079c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contate-nos<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04ba738 elementor-widget elementor-widget-heading\" data-id=\"04ba738\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">fale com um especialista agora<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36ef5a9 elementor-widget elementor-widget-text-editor\" data-id=\"36ef5a9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tEnfrente os desafios da sua organiza\u00e7\u00e3o com uma nova abordagem. Explore o potencial das solu\u00e7\u00f5es de drones e intelig\u00eancia artificial.\n\nDescubra como podemos ajud\u00e1-lo a impulsionar o seu neg\u00f3cio hoje!\n\nPreencha o formul\u00e1rio e nossa equipe entrar\u00e1 em contato com voc\u00ea!\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-693cf8d\" data-id=\"693cf8d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d9a5f0 elementor-button-align-start elementor-mobile-button-align-stretch elementor-widget elementor-widget-global elementor-global-14443 elementor-widget-form\" data-id=\"6d9a5f0\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Seguindo&quot;,&quot;step_previous_label&quot;:&quot;Antigo&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.21.0 - 20-05-2024 *\/\n.elementor-button.elementor-hidden,.elementor-hidden{display:none}.e-form__step{width:100%}.e-form__step:not(.elementor-hidden){display:flex;flex-wrap:wrap}.e-form__buttons{flex-wrap:wrap}.e-form__buttons,.e-form__buttons__wrapper{display:flex}.e-form__indicators{display:flex;justify-content:space-between;align-items:center;flex-wrap:nowrap;font-size:13px;margin-bottom:var(--e-form-steps-indicators-spacing)}.e-form__indicators__indicator{display:flex;flex-direction:column;align-items:center;justify-content:center;flex-basis:0;padding:0 var(--e-form-steps-divider-gap)}.e-form__indicators__indicator__progress{width:100%;position:relative;background-color:var(--e-form-steps-indicator-progress-background-color);border-radius:var(--e-form-steps-indicator-progress-border-radius);overflow:hidden}.e-form__indicators__indicator__progress__meter{width:var(--e-form-steps-indicator-progress-meter-width,0);height:var(--e-form-steps-indicator-progress-height);line-height:var(--e-form-steps-indicator-progress-height);padding-right:15px;border-radius:var(--e-form-steps-indicator-progress-border-radius);background-color:var(--e-form-steps-indicator-progress-color);color:var(--e-form-steps-indicator-progress-meter-color);text-align:right;transition:width .1s linear}.e-form__indicators__indicator:first-child{padding-left:0}.e-form__indicators__indicator:last-child{padding-right:0}.e-form__indicators__indicator--state-inactive{color:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-inactive [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-inactive-secondary-color,#fff)}.e-form__indicators__indicator--state-inactive object,.e-form__indicators__indicator--state-inactive svg{fill:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-active{color:var(--e-form-steps-indicator-active-primary-color,#39b54a);border-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active object,.e-form__indicators__indicator--state-active svg{fill:var(--e-form-steps-indicator-active-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed{color:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator--state-completed [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator__label{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator--shape-none{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a);background-color:initial}.e-form__indicators__indicator--state-completed object,.e-form__indicators__indicator--state-completed svg{fill:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator__icon{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);font-size:var(--e-form-steps-indicator-icon-size);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;overflow:hidden;margin-bottom:10px}.e-form__indicators__indicator__icon img,.e-form__indicators__indicator__icon object,.e-form__indicators__indicator__icon svg{width:var(--e-form-steps-indicator-icon-size);height:auto}.e-form__indicators__indicator__icon .e-font-icon-svg{height:1em}.e-form__indicators__indicator__number{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;margin-bottom:10px}.e-form__indicators__indicator--shape-circle{border-radius:50%}.e-form__indicators__indicator--shape-square{border-radius:0}.e-form__indicators__indicator--shape-rounded{border-radius:5px}.e-form__indicators__indicator--shape-none{border:0}.e-form__indicators__indicator__label{text-align:center}.e-form__indicators__indicator__separator{width:100%;height:var(--e-form-steps-divider-width);background-color:#babfc5}.e-form__indicators--type-icon,.e-form__indicators--type-icon_text,.e-form__indicators--type-number,.e-form__indicators--type-number_text{align-items:flex-start}.e-form__indicators--type-icon .e-form__indicators__indicator__separator,.e-form__indicators--type-icon_text .e-form__indicators__indicator__separator,.e-form__indicators--type-number .e-form__indicators__indicator__separator,.e-form__indicators--type-number_text .e-form__indicators__indicator__separator{margin-top:calc(var(--e-form-steps-indicator-padding, 30px) \/ 2 - var(--e-form-steps-divider-width, 1px) \/ 2)}.elementor-field-type-hidden{display:none}.elementor-field-type-html{display:inline-block}.elementor-field-type-tel input{direction:inherit}.elementor-login .elementor-lost-password,.elementor-login .elementor-remember-me{font-size:.85em}.elementor-field-type-recaptcha_v3 .elementor-field-label{display:none}.elementor-field-type-recaptcha_v3 .grecaptcha-badge{z-index:1}.elementor-button .elementor-form-spinner{order:3}.elementor-form .elementor-button>span{display:flex;justify-content:center;align-items:center}.elementor-form .elementor-button .elementor-button-text{white-space:normal;flex-grow:0}.elementor-form .elementor-button svg{height:auto}.elementor-form .elementor-button .e-font-icon-svg{height:1em}.elementor-select-wrapper .select-caret-down-wrapper{position:absolute;top:50%;transform:translateY(-50%);inset-inline-end:10px;pointer-events:none;font-size:11px}.elementor-select-wrapper .select-caret-down-wrapper svg{display:unset;width:1em;aspect-ratio:unset;fill:currentColor}.elementor-select-wrapper .select-caret-down-wrapper i{font-size:19px;line-height:2}.elementor-select-wrapper.remove-before:before{content:\"\"!important}<\/style>\t\t<form class=\"elementor-form\" method=\"post\" id=\"main_form\" name=\"Pouso corporativo\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"11194\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"6d9a5f0\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNomes e sobrenomes\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tCorreio eletr\u00f4nico\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_15463a4 elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_15463a4\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tTelefone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_15463a4]\" id=\"form-field-field_15463a4\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\" aria-required=\"true\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Apenas n\u00fameros e caracteres de telefone (#, -, *, etc.) s\u00e3o aceitos.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_6cc3e93 elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_6cc3e93\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tO neg\u00f3cio\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_6cc3e93]\" id=\"form-field-field_6cc3e93\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-message elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tPa\u00eds\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-caret-down\"><\/i>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[message]\" id=\"form-field-message\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t<option value=\"Selecione\">Selecione<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Argentina\">Argentina<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Brasil\">Brasil<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Chile\">Chile<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Colombia\">Colombia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Costa Rica\">Costa Rica<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"M\u00e9xico\">M\u00e9xico<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Peru\">Peru<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Panam\u00e1\">Panam\u00e1<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Rep\u00fablica Dominicana\">Rep\u00fablica Dominicana<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Outro\">Outro<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-field_522cc80 elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_522cc80\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tAssunto\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-caret-down\"><\/i>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[field_522cc80]\" id=\"form-field-field_522cc80\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t<option value=\"Selecione\">Selecione<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Solu\u00e7\u00f5es de an\u00e1lise e captura \">Solu\u00e7\u00f5es de an\u00e1lise e captura <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Solu\u00e7\u00f5es de seguran\u00e7a e defesa\">Solu\u00e7\u00f5es de seguran\u00e7a e defesa<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Solu\u00e7\u00f5es de log\u00edstica de carga\">Solu\u00e7\u00f5es de log\u00edstica de carga<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Venda de equipamentos\">Venda de equipamentos<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Suporte ao cliente\">Suporte ao cliente<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Outro\">Outro<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-field_b56606c elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_b56606c\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tConte-nos um pouco sobre sua necessidade\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[field_b56606c]\" id=\"form-field-field_b56606c\" rows=\"2\" required=\"required\" aria-required=\"true\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-html elementor-field-group elementor-column elementor-field-group-field_380987d elementor-col-100\">\n\t\t\t\t\tA UAV Latam tem o compromisso de proteger e respeitar a privacidade de todos os nossos clientes, e usaremos suas informa\u00e7\u00f5es pessoais apenas para administrar sua conta e fornecer os produtos e servi\u00e7os que voc\u00ea nos solicitou. De tempos em tempos, gostar\u00edamos de nos comunicar com voc\u00ea sobre nossos produtos e servi\u00e7os, bem como outros conte\u00fados que possam ser de seu interesse. Se voc\u00ea consentir que entremos em contato com voc\u00ea para esse fim, marque a caixa abaixo para indicar como voc\u00ea gostaria que entremos em contato com voc\u00ea:\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_8792e3b elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_8792e3b]\" id=\"form-field-field_8792e3b\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\" required=\"required\" aria-required=\"true\">\n\t\t\t\t<label for=\"form-field-field_8792e3b\">Eu concordo em receber outras comunica\u00e7\u00f5es da UAV Latam.<\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-html elementor-field-group elementor-column elementor-field-group-field_ff97bbd elementor-col-100\">\n\t\t\t\t\tAo clicar em enviar abaixo, voc\u00ea concorda que a UAV Latam armazena e processa as informa\u00e7\u00f5es pessoais enviadas acima para fornecer a voc\u00ea o conte\u00fado solicitado.\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_9e07550 elementor-col-100 recaptcha_v3-bottomleft\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_9e07550\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LcS1awcAAAAAM9m8rUCuQO2BuZpBy1Zh707HPW-\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomleft\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-sm\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\" elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Enviar<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb04e5a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb04e5a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d24d846\" data-id=\"d24d846\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d80644e elementor-widget elementor-widget-image\" data-id=\"d80644e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/uavlatam.com\/wp-content\/uploads\/2024\/06\/logo-uav-blanco-1-e1718906915187.png\" class=\"attachment-large size-large wp-image-15947\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5ffdd36\" data-id=\"5ffdd36\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9511026 elementor-widget elementor-widget-heading\" data-id=\"9511026\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Siga-nos em<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9116799 e-grid-align-left e-grid-align-mobile-center elementor-grid-2 elementor-shape-rounded elementor-widget elementor-widget-social-icons\" data-id=\"9116799\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-widget-social-icons.elementor-grid-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-mobile-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-tablet-0 .elementor-widget-container{line-height:1;font-size:0}.elementor-widget-social-icons:not(.elementor-grid-0):not(.elementor-grid-tablet-0):not(.elementor-grid-mobile-0) .elementor-grid{display:inline-grid}.elementor-widget-social-icons .elementor-grid{grid-column-gap:var(--grid-column-gap,5px);grid-row-gap:var(--grid-row-gap,5px);grid-template-columns:var(--grid-template-columns);justify-content:var(--justify-content,center);justify-items:var(--justify-content,center)}.elementor-icon.elementor-social-icon{font-size:var(--icon-size,25px);line-height:var(--icon-size,25px);width:calc(var(--icon-size, 25px) + 2 * var(--icon-padding, .5em));height:calc(var(--icon-size, 25px) + 2 * var(--icon-padding, .5em))}.elementor-social-icon{--e-social-icon-icon-color:#fff;display:inline-flex;background-color:#69727d;align-items:center;justify-content:center;text-align:center;cursor:pointer}.elementor-social-icon i{color:var(--e-social-icon-icon-color)}.elementor-social-icon svg{fill:var(--e-social-icon-icon-color)}.elementor-social-icon:last-child{margin:0}.elementor-social-icon:hover{opacity:.9;color:#fff}.elementor-social-icon-android{background-color:#a4c639}.elementor-social-icon-apple{background-color:#999}.elementor-social-icon-behance{background-color:#1769ff}.elementor-social-icon-bitbucket{background-color:#205081}.elementor-social-icon-codepen{background-color:#000}.elementor-social-icon-delicious{background-color:#39f}.elementor-social-icon-deviantart{background-color:#05cc47}.elementor-social-icon-digg{background-color:#005be2}.elementor-social-icon-dribbble{background-color:#ea4c89}.elementor-social-icon-elementor{background-color:#d30c5c}.elementor-social-icon-envelope{background-color:#ea4335}.elementor-social-icon-facebook,.elementor-social-icon-facebook-f{background-color:#3b5998}.elementor-social-icon-flickr{background-color:#0063dc}.elementor-social-icon-foursquare{background-color:#2d5be3}.elementor-social-icon-free-code-camp,.elementor-social-icon-freecodecamp{background-color:#006400}.elementor-social-icon-github{background-color:#333}.elementor-social-icon-gitlab{background-color:#e24329}.elementor-social-icon-globe{background-color:#69727d}.elementor-social-icon-google-plus,.elementor-social-icon-google-plus-g{background-color:#dd4b39}.elementor-social-icon-houzz{background-color:#7ac142}.elementor-social-icon-instagram{background-color:#262626}.elementor-social-icon-jsfiddle{background-color:#487aa2}.elementor-social-icon-link{background-color:#818a91}.elementor-social-icon-linkedin,.elementor-social-icon-linkedin-in{background-color:#0077b5}.elementor-social-icon-medium{background-color:#00ab6b}.elementor-social-icon-meetup{background-color:#ec1c40}.elementor-social-icon-mixcloud{background-color:#273a4b}.elementor-social-icon-odnoklassniki{background-color:#f4731c}.elementor-social-icon-pinterest{background-color:#bd081c}.elementor-social-icon-product-hunt{background-color:#da552f}.elementor-social-icon-reddit{background-color:#ff4500}.elementor-social-icon-rss{background-color:#f26522}.elementor-social-icon-shopping-cart{background-color:#4caf50}.elementor-social-icon-skype{background-color:#00aff0}.elementor-social-icon-slideshare{background-color:#0077b5}.elementor-social-icon-snapchat{background-color:#fffc00}.elementor-social-icon-soundcloud{background-color:#f80}.elementor-social-icon-spotify{background-color:#2ebd59}.elementor-social-icon-stack-overflow{background-color:#fe7a15}.elementor-social-icon-steam{background-color:#00adee}.elementor-social-icon-stumbleupon{background-color:#eb4924}.elementor-social-icon-telegram{background-color:#2ca5e0}.elementor-social-icon-threads{background-color:#000}.elementor-social-icon-thumb-tack{background-color:#1aa1d8}.elementor-social-icon-tripadvisor{background-color:#589442}.elementor-social-icon-tumblr{background-color:#35465c}.elementor-social-icon-twitch{background-color:#6441a5}.elementor-social-icon-twitter{background-color:#1da1f2}.elementor-social-icon-viber{background-color:#665cac}.elementor-social-icon-vimeo{background-color:#1ab7ea}.elementor-social-icon-vk{background-color:#45668e}.elementor-social-icon-weibo{background-color:#dd2430}.elementor-social-icon-weixin{background-color:#31a918}.elementor-social-icon-whatsapp{background-color:#25d366}.elementor-social-icon-wordpress{background-color:#21759b}.elementor-social-icon-x-twitter{background-color:#000}.elementor-social-icon-xing{background-color:#026466}.elementor-social-icon-yelp{background-color:#af0606}.elementor-social-icon-youtube{background-color:#cd201f}.elementor-social-icon-500px{background-color:#0099e5}.elementor-shape-rounded .elementor-icon.elementor-social-icon{border-radius:10%}.elementor-shape-circle .elementor-icon.elementor-social-icon{border-radius:50%}<\/style>\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-c4ace9c\" href=\"https:\/\/www.facebook.com\/UAV-Latam-106778171753035\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-ef9b91d\" href=\"https:\/\/www.linkedin.com\/company\/75580131\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-bc982f9\" href=\"https:\/\/www.instagram.com\/uavlatam\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-7a63af3\" href=\"https:\/\/www.youtube.com\/channel\/UC81PS0j_PN59zPVDw1qO00A\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1407a33\" data-id=\"1407a33\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6ac638 elementor-widget elementor-widget-heading\" data-id=\"e6ac638\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mesa principal<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-511f2b3 elementor-widget elementor-widget-text-editor\" data-id=\"511f2b3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>INNOVA 104, Edificio 104,<br \/>Escrit\u00f3rio 14 Cidade do Conhecimento,<br \/>Clayton, Rep\u00fablica de Panam\u00e1<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-640d157\" data-id=\"640d157\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9f536d elementor-widget elementor-widget-text-editor\" data-id=\"b9f536d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\n            <a href=\"https:\/\/uavlatam.com\/pt-br\/politicas-de-privacidad-de-datos-uso-de-cookies-y-anti-spam\/\" target=\"_blank\" rel=\"noopener\">Pol\u00edticas de privacidade, uso de cookies e anti-spam<\/a><br \/>\n            <br \/>\n            <a href=\"https:\/\/uavlatam.com\/pt-br\/politica-de-gestion-integrada\/\" target=\"_blank\" rel=\"noopener\">Pol\u00edtica de gest\u00e3o integrada<\/a><br \/>\n            <br \/>\n            <a href=\"https:\/\/uavlatam.com\/pt-br\/politica-de-hostigamiento-sexual\/\" target=\"_blank\" rel=\"noopener\">Pol\u00edtica de Ass\u00e9dio Sexual<\/a><br \/>\n            <br \/>\n            <a href=\"https:\/\/uavlatam.com\/pt-br\/canal-de-denuncias\/\" target=\"_blank\" rel=\"noopener\">Canal de reclama\u00e7\u00f5es<\/a>\n          <\/p>\n<p>\u00a9 2023 UAV Latam<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-baabdf6 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"baabdf6\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f616f95 elementor-hidden-mobile\" data-id=\"f616f95\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e98e7e elementor-widget elementor-widget-text-editor\" data-id=\"3e98e7e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00bfVoc\u00ea precisa de mais informa\u00e7\u00f5es?<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c727f9d\" data-id=\"c727f9d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1eb3aae elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"1eb3aae\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contactanos\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CONTATE-NOS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fe0affb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"fe0affb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5803dee\" data-id=\"5803dee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-272b590 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"272b590\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e7c9393\" data-id=\"e7c9393\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-070e538 elementor-view-stacked elementor-widget__width-auto elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"070e538\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/wa.me\/51989245123\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Come\u00e7ar Sobre N\u00f3s Solu\u00e7\u00f5es Blog Contate-nos Eng Esp Por Piloto de drone? \u00a0\u00a0 \u00a0Trabalhe conosco Come\u00e7ar Sobre n\u00f3s Solu\u00e7\u00f5es Blog Contate-nos Eng Esp Por Piloto de drone? \u00a0\u00a0 Trabalhe conosco CONTATE-NOS Transforme sua empresa com solu\u00e7\u00f5es avan\u00e7adas de drones Minimize riscos com solu\u00e7\u00f5es anti-drone.Transforme sua empresa com solu\u00e7\u00f5es avan\u00e7adas de dronesProteja ativos com solu\u00e7\u00f5es de [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-11194","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/uavlatam.com\/pt-br\/wp-json\/wp\/v2\/pages\/11194"}],"collection":[{"href":"https:\/\/uavlatam.com\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uavlatam.com\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uavlatam.com\/pt-br\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/uavlatam.com\/pt-br\/wp-json\/wp\/v2\/comments?post=11194"}],"version-history":[{"count":0,"href":"https:\/\/uavlatam.com\/pt-br\/wp-json\/wp\/v2\/pages\/11194\/revisions"}],"wp:attachment":[{"href":"https:\/\/uavlatam.com\/pt-br\/wp-json\/wp\/v2\/media?parent=11194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}